{"id":1063,"date":"2023-03-07T16:59:35","date_gmt":"2023-03-07T15:59:35","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=1063"},"modified":"2024-01-26T16:14:08","modified_gmt":"2024-01-26T15:14:08","slug":"fliesenarten-und-ihre-unterschiede","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/fliesenarten-und-ihre-unterschiede\/2023\/03","title":{"rendered":"Fliesenarten und ihre Unterschiede"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Welche Fliese darf es denn sein? Damit Sie genau die richtigen Fliesen f\u00fcr Ihr Projekt finden, haben wir f\u00fcr Sie eine \u00dcbersicht der gel\u00e4ufigsten Fliesenarten zusammengestellt \u2013 mit ihren Besonderheiten und Einsatzbereichen. <\/strong><\/p>\n<p>Sie sind auf der Suche nach Fliesen f\u00fcr Ihr neues Renovierungsprojekt? Je nach individueller Beanspruchung, Zweck und Einsatzort kommen unterschiedliche Fliesen infrage. Wir kl\u00e4ren von Steingut- \u00fcber Feinsteinzeug- bis hin zu Glasfliesen auf und verraten, auf welche Eigenschaften Sie beim Kauf der Fliesenarten achten sollten.<\/p>\n<h2>Diese Merkmale sind bei allen Fliesenarten wichtig<\/h2>\n<h3>Rektifiziert<\/h3>\n<p>Steinzeugfliesen werden in Formen gepresst und anschlie\u00dfend gebrannt. Um eine exakte Formgebung zu gew\u00e4hrleisten, werden die Kanten auf einen Winkel von 90\u00b0 gebracht \u2013 also rektifiziert. So entstehen klare, geradlinige und ma\u00dfgenaue Verlegemuster.<\/p>\n<h3>Glasiert vs unglasiert<\/h3>\n<p>Glasierte Fliesen sind s\u00e4urebest\u00e4ndig, wasserabweisend und UV-best\u00e4ndig. Unglasierte Fliesen besitzen hingegen eine raue Oberfl\u00e4che und nehmen Wasser auf. F\u00fcr den Nassbereich sind sie somit ungeeignet. Sie sind jedoch wesentlich langlebiger und robuster. Zudem wirkt die Oberfl\u00e4che rutschhemmend, was die Trittsicherheit erh\u00f6ht.<\/p>\n<h3>Abriebgruppe<\/h3>\n<p>Fliesen nutzen sich bei mechanischer Beanspruchung allm\u00e4hlich ab. Beim Kauf von Fliesen sollten Sie daher die Abriebgruppe beachten. Sie ber\u00fccksichtigt, wie h\u00e4ufig Sie die Fliesen begehen und welche Schuhe Sie tragen (z. B. harte oder weiche Sohlen, barfu\u00df). Es werden f\u00fcnf Abriebgruppen unterschieden:<\/p>\n<p>&#8211; I: sehr leichte Beanspruchung, z. B. Wandfliesen<\/p>\n<p>&#8211; II: leichte Beanspruchung, barfu\u00df und Hausschuhe<\/p>\n<p>&#8211; III: mittlere Beanspruchung, Schuhe in Schlafzimmer \/ Bad \/ Wohnzimmer<\/p>\n<p>&#8211; IV: st\u00e4rkere Beanspruchung, Treppen \/ Flur \/ K\u00fcche<\/p>\n<p>&#8211; V: starke Beanspruchung, alle Wohnbereiche \/ Terrasse \/ Balkon<\/p>\n<h3>Rutschfestigkeit<\/h3>\n<p>Die Rutschfestigkeit, oder auch Trittsicherheit, wird in Rutschhemmklassen angegeben. Sie geben an, ab welchem Neigungswinkel eine Person auf einer ge\u00f6lten Fl\u00e4che zu rutschen beginnt. Dabei werden f\u00fcnf Klassen von R9 bis R13 unterschieden, wobei R9 die Klasse mit der niedrigsten Rutschhemmung darstellt. Im privaten Bereich reicht R9 aus. F\u00fcr Nasszellen und Barfu\u00dfbereiche kommen zus\u00e4tzlich Kategorien von A bis C zur weiteren Abstufung hinzu.<\/p>\n<h2>Diese Fliesenarten sollten Sie kennen<\/h2>\n<h3>Keramikfliesen<\/h3>\n<p>Sie sind die beliebteste und h\u00e4ufigste Fliesenart: Keramikfliesen. Die Zusammensetzung aus <strong>Ton, Sand, Feldspan<\/strong> und <strong>weiteren Rohstoffen<\/strong> macht Keramik zu einem <strong>widerstandsf\u00e4higen<\/strong> und <strong>vielseitigen<\/strong> Material. Unter Hinzugabe von Wasser werden die verschiedenen Bestandteile gemischt und anschlie\u00dfend unter hohen Druck gepresst. Je nach Art und gew\u00fcnschter Beschaffenheit werden die Fliesen anschlie\u00dfend bei hohen Temperaturen von bis zu 1.300\u00b0C gebrannt. Keramikfliesen gibt es sowohl f\u00fcr den Innen- und Au\u00dfenbereich, als auch als Boden- und Wandfliesen. Sie imitieren sogar Stein-, Holz- und Betonoptiken.<\/p>\n<h3>Steingutfliesen<\/h3>\n<p>Durch ihre por\u00f6se Struktur ist die Steingutfliese <strong>nicht besonders widerstandsf\u00e4hig<\/strong>. Das liegt am Herstellungsverfahren. Sie wird bei nicht ganz so hohen Temperaturen zwischen 900\u00b0C und 1100\u00b0C gebrannt. Das treibt den Scherben vor allem Wasser aus und es entstehen Poren. Steingutfliesen nehmen deshalb besonders schnell Feuchtigkeit auf und sind so nur im Innenbereich als Wandfliese einsetzbar.<\/p>\n<p>Doch sie haben auch ihre <strong>Vorteile<\/strong>: Steingutfliesen lassen sich <strong>einfach verarbeiten<\/strong> und sch\u00f6n <strong>dekorieren<\/strong>. M\u00fcssen Sie Aussparungen an Ecken oder Rohren zuschneiden, haben Sie bei Steingut leichtes Spiel. Zum Schutz vor oberfl\u00e4chlicher Feuchtigkeit werden Steingutfliesen meist zweifach glasiert.<\/p>\n<h3>Steinzeugfliesen<\/h3>\n<p>Im Unterschied zu Steingut besteht Steinzeug aus <strong>Feinkeramik<\/strong>. Die Fliesen werden trockengepresst und anschlie\u00dfend bei Temperaturen zwischen 1.150\u00b0C und 1.300\u00b0C gebrannt. Dabei verschmilzt das Material und wird so stark verdichtet, dass es sehr fest wird. Die Fliese nimmt kaum noch Wasser auf und ist somit <strong>frostbest\u00e4ndig<\/strong> und <strong>abriebfest<\/strong>. Dank der robusten Eigenschaften k\u00f6nnen Steinzeugfliesen auch im Au\u00dfenbereich zum Einsatz kommen.<\/p>\n<h3>Feinsteinzeugfliesen<\/h3>\n<p>Feinsteinzeugfliesen werden unter sehr hohem Druck gepresst und unter Zugabe des Rohstoffes <strong>Feldspat <\/strong>bei bis zu 1300\u00b0C gebrannt. Feldspat ist ein Mineral (Silikat), das einen niedrigen Schmelzpunkt besitzt. Beim Brennvorgang verschmelzen daher die Materialien fast vollst\u00e4ndig miteinander. Dadurch nehmen Feinsteinzeugfliesen nur noch sehr wenig Fl\u00fcssigkeit auf. Wie wasserdurchl\u00e4ssig ein Material ist, wird in Prozent angegeben. Bei Feinsteinzeugfliesen liegt der Wert unter 0,5%. Einigen Herstellern gelingt es sogar, Fliesen mit einer Wasseraufnahme von 0,03% herzustellen. Zum Vergleich: Glas hat einen Wert von 0,02%.<\/p>\n<p>Feinsteinzeug ist eine sehr <strong>robusteste Fliesenart<\/strong>. Sie k\u00f6nnen Feinsteinzeugfliesen ohne Probleme im Innen- und Au\u00dfenbereich, an den W\u00e4nden und als Bodenfliese verlegen. Wie rutschfest die Fliesen sind, entscheidet die Oberfl\u00e4chenstruktur. Diese erhalten die Fliesen mithilfe eines Stempels oder durch den Einsatz von Granulat. Polierte Oberfl\u00e4chen entstehen durch Schleifen. In den meisten F\u00e4llen muss die Oberfl\u00e4chen zus\u00e4tzlich impr\u00e4gniert werden.<\/p>\n<h3>Natursteinfliesen<\/h3>\n<p>Im Gegensatz zu Fliesen aus Steingut kommen bei Natursteinfliesen \u2013 wie es der Name erahnen l\u00e4sst \u2013 <strong>echte Steinarten<\/strong> zum Einsatz. Granit, Marmor, Schiefer oder Travertin \u2013 die Liste ist lang. Jedes Gestein bringt seine ganz eigenen Charaktereigenschaften mit. Entscheidende Faktoren f\u00fcr den jeweiligen Zweck und Einsatzort sind u. a. die <strong>S\u00e4urebest\u00e4ndigkeit<\/strong> und die <strong>Feuchtigkeitsresistenz<\/strong>. Je nachdem m\u00fcssen die Natursteinfliesen impr\u00e4gniert und vor \u00e4u\u00dferen Einfl\u00fcssen gesch\u00fctzt werden. Gesch\u00e4tzt wird diese Fliesenart vor allem f\u00fcr ihren unvergleichlichen Look. Naturstein wird nicht etwa aus einem Gemisch gepresst\u00a0 und gebrannt, sondern als nat\u00fcrlich gewachsenes Material bearbeitet. Farbe, Struktur, Maserung unterscheidet sich von Fliese zu Fliese, wodurch <strong>spannende Verlegemuster und Fliesenfl\u00e4chen<\/strong> entstehen.<\/p>\n<h3>Zementfliesen<\/h3>\n<p>Anders als Feinsteinzeugfliesen werden Zementfliesen nicht gebrannt, sondern <strong>getrocknet<\/strong>. Dieser Prozess macht sie wesentlich por\u00f6ser. Durch die Struktur nehmen Zementfliesen leicht Wasser auf, wodurch sie <strong>nicht frostsicher<\/strong> sind \u2013 f\u00fcr den Au\u00dfenbereich sind sie also g\u00e4nzlich ungeeignet. Beim Einsatz in Innenr\u00e4umen werden die Fliesen zus\u00e4tzlich<strong> impr\u00e4gniert<\/strong>, um Schmutz und Fett abzuweisen. Der Vorteil: Zementfliesen bestechen durch eine <strong>samtige und weiche Haptik<\/strong>. Da sie oft noch in Handarbeit hergestellt werden, bewahren sie sich eine einmalige Optik.<\/p>\n<h3>Fliesenart Glasfliesen<\/h3>\n<p>\u00c4hnlich wie Feinsteinzeugfliesen weisen Glasfliesen eine <strong>hohe Dichte<\/strong> auf und sind nahezu <strong>wasserundurchl\u00e4ssig<\/strong>. Das hat allerdings zur Folge, dass sie schnell <strong>rutschig<\/strong> werden. Deshalb kommen Glasfliesen fast ausschlie\u00dflich als Wandfliese zum Einsatz. Besonders gesch\u00e4tzt werden sie f\u00fcr ihre vielf\u00e4ltige Kolorierung als auch f\u00fcr den transparenten Look, der fabelhafte Lichtspiele erm\u00f6glicht.<\/p>\n<h2>Fazit<\/h2>\n<p>Nun kennen Sie alle Merkmale der unterschiedlichen Fliesenarten und sind gut ger\u00fcstet, auf die Suche nach der passenden Fliese zu kennen. Schauen Sie am besten direkt im Online-Shop von Franke Raumwert nach und lassen sie sich von den s<a href=\"https:\/\/www.franke-raumwert.de\/\" target=\"_blank\" rel=\"noopener\">ch\u00f6nsten Kollektionen verschiedener Marken<\/a> inspirieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Welche Fliese darf es denn sein? Damit Sie genau die richtigen Fliesen f\u00fcr Ihr Projekt finden, haben wir f\u00fcr Sie eine \u00dcbersicht der gel\u00e4ufigsten Fliesenarten zusammengestellt \u2013 mit ihren Besonderheiten und Einsatzbereichen. Sie sind auf der Suche nach Fliesen f\u00fcr Ihr neues Renovierungsprojekt? Je nach individueller Beanspruchung, Zweck und Einsatzort kommen unterschiedliche Fliesen infrage. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"Fliesenarten und ihre Unterschiede - Franke Raumwert","_seopress_titles_desc":"Damit Sie die richtigen Fliesen f\u00fcr Ihr Projekt finden, haben wir eine \u00dcbersicht der Fliesenarten zusammengestellt.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Fliesenarten","footnotes":""},"categories":[7],"tags":[],"class_list":["post-1063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":6,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"predecessor-version":[{"id":5359,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1063\/revisions\/5359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/5137"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}