{"id":1855,"date":"2017-12-11T13:53:46","date_gmt":"2017-12-11T12:53:46","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=1855"},"modified":"2024-01-26T17:27:18","modified_gmt":"2024-01-26T16:27:18","slug":"fliesenspiegel-kueche","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/fliesenspiegel-kueche\/2017\/12","title":{"rendered":"Fliesenspiegel in der K\u00fcche: Materialien im Check!"},"content":{"rendered":"<p><strong><br \/>\nZu jeder K\u00fcche geh\u00f6rt ein Fliesenspiegel, um die Wand zwischen Arbeitsplatte und K\u00fcchenoberschr\u00e4nken vor Fett, Wasser oder Schmutz zu sch\u00fctzen. Urspr\u00fcnglich war die Wand mit Fliesen verkleidet, mittlerweile kommt eine F\u00fclle an Materialien zum Einsatz.\u00a0<\/strong><\/p>\n<h2>Fliesen<\/h2>\n<p>Wer meint, dass Fliesen in der K\u00fcche immer altbacken aussehen, der irrt. Sicher ist allerdings: Am Zustand eines Fliesenspiegels l\u00e4sst sich schnell das Alter einer K\u00fcche ablesen. Aber welche Fliesen sind f\u00fcr heutige K\u00fcchen eigentlich besonders sch\u00f6n? Wir haben drei Beispiele:<\/p>\n<h3>Wei\u00dfe Fliesen im Landhausstil<\/h3>\n<p>F\u00fcr Hausherren, die eine K\u00fcche im Landhausstil einrichten m\u00f6chten, sind Fliesen eine wundersch\u00f6ne M\u00f6glichkeit, das nat\u00fcrliche Flair eines solchen Stils wirken zu lassen. Die wei\u00dfen, quadratischen Fliesen im Bild passen wie angegossen zu der hellen Einrichtung der K\u00fcche und sind eine sch\u00f6ne Erg\u00e4nzung zum rustikalen Fu\u00dfboden oder Esstisch. Tipp: Quadratische Ma\u00dfe passen am besten zum Landhausstil und wirken authentisch.<\/p>\n<h3>Akzente setzen mit Mosaikfliesen<\/h3>\n<p><a href=\"\/Fliesenwelten\/TW-Mosaik\/\">Mosaikfliesen<\/a>, mit denen sich sch\u00f6ne Highlights setzen lassen, ist den meisten Hausbewohnern vor allem im Badezimmer ein Begriff. In der K\u00fcche k\u00f6nnen Mosaikfliesen einen \u00e4hnlich aufregenden Effekt haben. W\u00e4hrend der Fliesenspiegel passend zu den K\u00fcchenmodulen und M\u00f6beln in Pastellbau integriert wurde, ist die Wandfl\u00e4che zwischen Herd und Dunstabzugshaube mit Mosaikfliesen gestaltet. Durch die ansonsten symmetrische Anordnung der K\u00fcche bildet der Herd auf diese Weise einen interessanten Blickfang. Praktischer Nebeneffekt: Auf den Mosaiksteinen sieht man Schmutz oder Fettspritzer nicht ganz so schnell.<\/p>\n<h3>Farbenfrohe Fliesenspiegel<\/h3>\n<p>Ein farbiger Fliesenspiegel bringt Leben in eine K\u00fcchengestaltung. Dabei sind dem eigenen Geschmack, was die Farbe angeht, kaum Grenzen gesetzt. Denn der Markt gibt beinahe alles her, was der Kunde sich w\u00fcnscht. Wichtig bei kr\u00e4ftigen Farben f\u00fcr den Fliesenspiegel: Die Schrankmodule der K\u00fcche sollten entweder in der gleichen Farbe oder neutral gestaltet sein. Sonst wirkt die Optik erdr\u00fcckend und man sieht sich schnell daran satt.<\/p>\n<h2>Holz<\/h2>\n<p>Holz ist bis heute eines der beliebtesten Materialien in K\u00fcchen. Und so ist es kaum ein Wunder, dass immer mehr Menschen nach einer K\u00fcchenr\u00fcckwand fragen, die aus Holz ist. Es erzeugt einerseits eine rustikale, gem\u00fctliche Atmosph\u00e4re. Doch weil Holz unglaublich wandelbar ist, l\u00e4sst es sich auch in minimalistischen Designs mit gradlinigen Formen integrieren. Eine K\u00fcchenr\u00fcckwand aus Holz holt visuell die Natur ein St\u00fcckchen ins Innere eines Hauses \u2013 ein Effekt, den sich viele Menschen w\u00fcnschen. Besonders sch\u00f6n ist \u00fcbrigens eine einheitliche Gestaltung von Arbeitsplatte und R\u00fcckwand. Das bringt eine gro\u00dfe Einheitlichkeit in die Optik. Welches Holz man f\u00fcr die Wand verwenden m\u00f6chte, h\u00e4ngt in erster Linie vom Kunden ab. Zu empfehlen sind Harth\u00f6lzer wie Eiche, Buche oder Nussbaum, da sie sehr robust sind. Vorteil von Holz: Es passt zu vielen verschiedenen Materialien und Farben der K\u00fcchenfronten. Aber Achtung: Das Holz sollte vorbehandelt und lasiert sein, damit es Schmutz und Fett gut verkraften kann. Regelm\u00e4\u00dfige Pflege ist Pflicht.<\/p>\n<p><em><strong>\u00dcbrigens:<\/strong> Wer die Holzoptik in der K\u00fcche liebt, aber gerne auf die robuste Qualit\u00e4t von Fliesen setzt, kann das problemlos tun. Fliesen werden mittlerweile auch in <a href=\"\/Fliesenwelten\/TW-Holzoptik\/\">Holzoptik<\/a> angeboten und sehen dem echten Material t\u00e4uschen \u00e4hnlich!<\/em><\/p>\n<h2>Acrylglas<\/h2>\n<p>Plexiglas (Acrylglas) kommt f\u00fcr K\u00fcchen infrage, die eine sehr moderne Gestaltung haben und sich eine ruhige Gestaltung zunutze machen. Das Material wird in vielen Farbt\u00f6nen, transparent oder mit Milchglas-Optik hergestellt. Besonders sch\u00f6n ist zum Beispiel eine individuelle Gestaltung des Fliesenspiegels: Hinter der durchsichtigen Plexiglasplatte lassen sich eigene Bilder oder eine Fototapete hinterlegen, die f\u00fcr eine individuelle Wirkung in der K\u00fcche sorgt. Nachteile von Plexiglas: Es ist nicht sehr kratzfest und geh\u00f6rt nicht hinter den Herd. Die hohen Temperaturen k\u00f6nnten das Material besch\u00e4digen.<\/p>\n<h2>Edelstahl<\/h2>\n<p>Das hochwertige Material Edelstahl ist in erster Linie aus Gro\u00dfk\u00fcchen, zum Beispiel in der Gastronomie, bekannt. Es hat einige unschlagbare Vorteile neben seinem attraktiven \u00c4u\u00dferen. Es kann problemlos mit Schmutz, Fett oder hei\u00dfen Spritzern umgehen und l\u00e4sst sich leicht reinigen. Aber Achtung: Auf Edelstahlfl\u00e4chen sieht man schnell jeden Fingerdruck. Wer damit ein Problem hat, sollte lieber die Finger von Edelstahl lassen.<\/p>\n<h2>Ziegel<\/h2>\n<p>Wer in alten Geb\u00e4uden lebt, hat vielleicht die eine oder andere Wand aus Ziegelmauerwerk in seinem Haus, die er freilegen m\u00f6chte. Oder die K\u00fcche soll eventuell ein urbanes, ja industrielles Design erhalten, was sich durch K\u00fcchenr\u00fcckw\u00e4nde mit Backsteinen gut nachempfinden l\u00e4sst? Das ist in der K\u00fcche bei guter Vorbereitung der Wand problemlos m\u00f6glich. Allerdings sollte im Bereich der Kochplatten eine Glasplatte vor dem Ziegelmauerwerk angebracht werden, um das Material zu sch\u00fctzen.<\/p>\n<h2>Latexfarbe<\/h2>\n<p>Manche K\u00fcchenliebhaber m\u00f6gen \u00fcberhaupt keine auff\u00e4llige Gestaltung der R\u00fcckenw\u00e4nde zwischen Arbeitsplatte und Oberschr\u00e4nken. Auch f\u00fcr diese F\u00e4lle hat der Handel vorgesorgt. Mit Lackfarben k\u00f6nnen die W\u00e4nde problemlos in allen Farben gestrichen werden und zieren so die K\u00fcche fugenlos. Dabei hat Latex Vor- und Nachteile. Latex ist abwaschbar und l\u00e4sst sich sehr strapazieren. Die sogenannte Scheuerklassenbest\u00e4ndigkeit auf den Produkten gibt an, nach wie vielen Scheuerbewegungen man mit Einbu\u00dfen der Farbe zu rechnen hat. Nachteil von Latex: Latexfarbe l\u00e4sst keinen Feuchtigkeitsaustausch, was m\u00f6glicherweise zu Schimmelbildung f\u00fchren kann. Wenn aber nicht die gesamte K\u00fcche mit einer solchen Farbe gestrichen wird, ist das Risiko mehr als \u00fcberschaubar.<\/p>\n<h2>Tafellack<\/h2>\n<p>Der Tafellack erinnert uns an Schultafeln aus fr\u00fcheren Schulzeiten und kommt in privaten Wohnr\u00e4umen immer mehr zum Einsatz \u2013 auch im Bereich der K\u00fcchenr\u00fcckw\u00e4nde. Es kann den Morgen mit fr\u00f6hlichen Botschaften aufpeppen, wichtige Termine beinhalten oder die aktuelle Einkaufsliste. Eine solche Optik, die einen fr\u00f6hliche, aber auch provisorische Nuance hat, muss man m\u00f6gen und ist vor allem f\u00fcr Familien eine sch\u00f6ne Idee.<\/p>\n<p>Der Lack zeichnet sich durch eine matte Optik aus und ist nat\u00fcrlich abwaschbar. Hei\u00dfe Spritzer wie hinter dem Herd mag er allerdings nicht und auch Tafellack sollte deswegen mit einer Glasplatte gesch\u00fctzt werden. Alternativ l\u00e4sst sich in diesem Bereich ein anderes Material, zum Beispiel eine Fliese oder eine Platte aus Edelstahl, setzen.<\/p>\n<h2>Beton<\/h2>\n<p>Als Material f\u00fcr moderne Wohnr\u00e4ume ist Sichtbeton ein beliebtes Material geworden, das auch in K\u00fcchen immer mehr Einzug h\u00e4lt. Wer seiner K\u00fcche einen modernen, n\u00fcchternen Look verpassen will, liegt mit einer K\u00fcchenr\u00fcckwand aus Beton genau richtig. Am einfachsten geht das mit <a href=\"\/Fliesenwelten\/TW-Betonoptik\/\">Fliesen in Betonoptik<\/a>. Sie sehen dem Underdog Beton t\u00e4uschend \u00e4hnlich, das Material ist allerdings ein unempfindliches Feinsteinzeug, das glasiert oder unglasiert sein kann.<\/p>\n<div class=\"shariff\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Ffliesenspiegel-kueche%2F2017%2F12\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Ffliesenspiegel-kueche%2F2017%2F12&text=Fliesenspiegel%20in%20der%20K%C3%BCche%3A%20Materialien%20im%20Check%21\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Ffliesenspiegel-kueche%2F2017%2F12&media=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fwp-content%2Fuploads%2F2017%2F12%2Fam_universe_beige_natural_60x120_oxide_natural_60x120_kb_sd.jpg&description=Fliesenspiegel%20in%20der%20K%C3%BCche%3A%20Materialien%20im%20Check%21\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span class=\"shariff-text\">merken<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Zu jeder K\u00fcche geh\u00f6rt ein Fliesenspiegel, um die Wand zwischen Arbeitsplatte und K\u00fcchenoberschr\u00e4nken vor Fett, Wasser oder Schmutz zu sch\u00fctzen. Urspr\u00fcnglich war die Wand mit Fliesen verkleidet, mittlerweile kommt eine F\u00fclle an Materialien zum Einsatz.\u00a0 Fliesen Wer meint, dass Fliesen in der K\u00fcche immer altbacken aussehen, der irrt. Sicher ist allerdings: Am Zustand eines Fliesenspiegels [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"Fliesenspiegel in der K\u00fcche: Materialien im Check!","_seopress_titles_desc":"Urspr\u00fcnglich war die Wand mit Fliesen verkleidet, mittlerweile kommt eine F\u00fclle an Materialien zum Einsatz.\u00a0","_seopress_robots_index":"","_seopress_analysis_target_kw":"Fliesenspiegel","footnotes":""},"categories":[10,33,3],"tags":[],"class_list":["post-1855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wandfliesen","category-kueche","category-wohnideen"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=1855"}],"version-history":[{"count":11,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1855\/revisions"}],"predecessor-version":[{"id":6003,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/1855\/revisions\/6003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/6000"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=1855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=1855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=1855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}