{"id":2025,"date":"2018-02-20T09:07:21","date_gmt":"2018-02-20T08:07:21","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=2025"},"modified":"2024-01-26T17:26:44","modified_gmt":"2024-01-26T16:26:44","slug":"fliesenkauf-worauf-achten","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/fliesenkauf-worauf-achten\/2018\/02","title":{"rendered":"Worauf Sie beim Fliesenkauf achten sollten"},"content":{"rendered":"<p>Fliesen sind wieder voll im Trend. Aus diesem Grund lassen sich Hersteller aller Art auch einiges einfallen, um ihre Produkte m\u00f6glichst hochwertig herzustellen. Dies beginnt bei den Qualit\u00e4tsmerkmalen, geht weiter \u00fcber die Optik und Gr\u00f6\u00dfe und endet bei den speziellen Eigenschaften, die bei entsprechender Fliesenwahl entscheidend sind. Aufgrund der sich uns bietenden breiten Auswahl ist es gar nicht so einfach, die richtigen Fliesen zu finden. Und Sie haben vermutlich Recht, beim Fliesenkauf lohnt es sich, besser zweimal \u00a0hinzusehen. Immerhin ist ein Boden nichts, was man bei Nichtgefallen binnen weniger Monate einfach wieder austauschen kann. Worauf Sie beim Fliesenkauf achten sollen, verraten wir in diesem Artikel.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2027 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf.png\" alt=\"Infografik Fliesenkauf\" width=\"2400\" height=\"9375\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf.png 2400w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-77x300.png 77w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-768x3000.png 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-262x1024.png 262w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-696x2719.png 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-1068x4172.png 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2018\/02\/Infografik_Fliesenkauf-1920x7500.png 1920w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/><\/p>\n<h2>Verwendungszweck Fliese \u2013 welche Arten kommen in Frage?<\/h2>\n<p>Lassen wir das Designe zun\u00e4chst ein wenig im Hintergrund stehen und besch\u00e4ftigen uns mit der Fliesenart, bzw. der Nutzung des Bodens. Dabei kommt es darauf an, wo die Fliesen verlegt werden sollen. Hier fallen Kriterien wie Beanspruchung, Rutschsicherheit und Wasseraufnahme enorm ins Gewicht und bestimmen, welche Art Fliese es werden sollte. Wir unterscheiden:<\/p>\n<ul>\n<li>Keramikfliesen<\/li>\n<li><em>Steingutfliesen<\/em><\/li>\n<li><em>Steinzeug- und Feinsteinzeugfliesen <\/em><\/li>\n<li>Natursteinfliesen<\/li>\n<li>Glasierte und unglasierte Fliesen<\/li>\n<\/ul>\n<p>Bekannt, und klassischerweise h\u00e4ufig in Verwendung, sind die Keramikfliesen. Sie unterscheiden sich in ihren Kategorien Steingut, Steinzeug und Feinsteinzeug. Hergestellt werden sie aus einem Gemisch aus Ton, Sand und Feldspat. Zu unterscheiden sind die Keramikfliesen schlie\u00dflich aufgrund ihrer speziellen Zusammensetzung und der Brenntemperatur.<\/p>\n<h3>Steingutfliesen oder Steinzeugfliesen?<\/h3>\n<p>Die typischen Steingutfliesen sind eher grobporig, k\u00f6nnen einfach zugeschnitten werden und sind besonders einfach zu verlegen. Bereiche, welche stark und h\u00e4ufig belastet werden, sind perfekt f\u00fcr Steingut. Allerdings sind diese Zusammensetzungen nicht frostsicher und k\u00f6nnen leicht por\u00f6s werden, weshalb sie \u00fcberwiegend im Innenbereich Verwendung finden sollten. Im Badezimmer nutzt man sie\u00a0 in den meisten F\u00e4llen in glasiertem Zustand.<\/p>\n<p>Beim Steinzeug handelt es sich um ein wesentlich dichteres Material, welches nur geringf\u00fcgig Wasser aufnehmen kann. Dies macht das Material sehr robust und vor allem frostsicher. Auch gegen S\u00e4ure oder Abrieb und Verschlei\u00df ist das Steinzeug gut gewappnet. Sie sind ideal als <a href=\"\/Bodenfliesen\/\">Bodenfliesen<\/a> geeignet und k\u00f6nnen sowohl Innen, als auch Au\u00dfen, verwendet werden. Auch dann, wenn man eher die unglasierte Version bevorzugt.<\/p>\n<p>Feinsteinzeugfliesen bieten eine extrem hohe Strapazierf\u00e4higkeit, sie sind frostsicher und eignen sich \u00fcberall f\u00fcr stark beanspruchte Fl\u00e4chen.<\/p>\n<h3>Sind Natursteinfliesen eine gute Wahl?<\/h3>\n<p>Natursteinfliesen bestehen meist aus Granit oder Marmor, wobei es sie auch als Sandstein, Schiefer oder Kalkstein zu kaufen gibt. Nat\u00fcrliche Materialien sind Geschmackssache, werden aber immer beliebter. Sie lassen die Raumgestaltung individueller und lebendiger wirken und sind gleicherma\u00dfen ziemlich robust.<\/p>\n<h3>Glasierte oder unglasierte Fliesen kaufen?<\/h3>\n<p>Die Unterschiede beider Varianten liegen klar auf der Hand. W\u00e4hrend die glasierten Fliesen sehr schmutzabweisend und einfach zu reinigen sind, sind unglasierte Fliesen sehr anf\u00e4llig f\u00fcr Kratzer. Vorteilhaft ist aber, dass unglasierte Fliesen nicht zu rutschig sind und glasierte Fliesen poliert werden m\u00fcssen.<\/p>\n<h3>Auf die Abriebklasse achten<\/h3>\n<p>Fliesen werden in Abriebklassen unterteilt, die in f\u00fcnf verschiedene Einstufungen unterteilt sind. Sie reichen von I \u2013 V. Abriebklasse I eignet sich f\u00fcr den privaten Wohnbereich und h\u00e4lt leichten Beanspruchungen des Alltages stand. F\u00fcr Badezimmer werden schon die Abriebklassen II und III empfohlen, wobei es sich um leichte und mittlere Beanspruchungen handelt. Abriebklasse IV wird im gewerblichen Bereich, f\u00fcr Verkaufsr\u00e4ume und Schulen, ben\u00f6tigt. Letztere Abriebklasse V geh\u00f6rt ebenfalls zu den starken Beanspruchungen und ist h\u00e4ufig in Krankenh\u00e4usern, in Banken oder Autoh\u00e4usern zu sehen.<\/p>\n<h2>Tritt- und Rutschsicherheit von Fliesen beachten<\/h2>\n<p>Fliesen m\u00fcssen nicht zwingend aalglatt sein und das t\u00e4gliche Leben gef\u00e4hrden. Vor allem im Treppenbereich k\u00f6nnten sehr glatte Fliesen zur Gefahr f\u00fcr Kinder werden. Aus diesem Grund darf man beim Kauf ruhig einen Blick auf die zwei Trittsicherheitsklassen werfen. Die Rutschsicherheit wird dabei mit R9 bis R13 gekennzeichnet, &#8211; leichte bis \u00a0hohe Anforderung.<\/p>\n<p>Bei Fl\u00e4chen, die generell und h\u00e4ufig barfu\u00df betreten werden, gelten die Bezeichnungen A, B und C f\u00fcr geringe bis hohe Rutschsicherheit. Im privaten Bereich kann man sich hier noch frei entscheiden, in gewerblichen R\u00e4umen sind gewisse Einstufungen sogar vorgeschrieben. Beispielsweise muss die Rutschsicherheitsklasse in Schwimmb\u00e4dern bei C liegen.<\/p>\n<h2>Die richtige Fliesengr\u00f6\u00dfe w\u00e4hlen<\/h2>\n<p>Fliesen gibt es in inzwischen allen erdenklichen Gr\u00f6\u00dfen. Die kleinsten Fliesenformate werden als Mosaikfliesen bezeichnet, man findet sie h\u00e4ufig an Badezimmerw\u00e4nden. Sie bieten ein hohes Potenzial an individuellen Gestaltungsm\u00f6glichkeiten und sind daher perfekt f\u00fcr schicke Designerwerke geeignet. Nachteilig zu nennen ist allerdings der hohe Zeitaufwand, der beim Verlegen der kleinen Fliesen einhergeht.<\/p>\n<p>Gro\u00dfe Fliesen und <a href=\"\/Fliesenwelten\/TW-XXL---Fliesen\/\">XXL Fliesen<\/a> sind generell etwas einfacher zu verlegen und schaffen ein durchweg klares Bild. Die Gestaltung ist clean, der Raum wirkt ruhiger und einheitlicher. Kleine R\u00e4ume k\u00f6nnen je nach Gr\u00f6\u00dfe der Fliese gr\u00f6\u00dfer wirken. Leider lassen sich die gro\u00dfen Fliesen bei Rissen oder Br\u00fcchen nur schwer austauschen. Auch m\u00fcssen sie aufw\u00e4ndiger gepflegt werden, je nach Beschaffenheit und Material versteht sich.<\/p>\n<h2>Wie viel Fliesen ben\u00f6tigte ich?<\/h2>\n<p>Beim Fliesenkauf gilt es, sich m\u00f6glichst nicht zu verrechnen. Wer zu viel kauft, der zahlt im Endeffekt drauf. Wer zu wenig bestellt, der steht irgendwann ohne Material auf der Baustelle und muss warten, ehe das Projekt Fliesenlegen weitergehen kann. Die korrekte Berechnung der Fliesenanzahl ist aber gar nicht so schwer, vorausgesetzt man kennt die korrekte Quadratmetersumme seiner R\u00e4ume.<\/p>\n<p>Die Breite mal die L\u00e4nge eines Raumes beschreiben die Fliesenfl\u00e4che in Quadratmeter. Einige Fliesen m\u00fcssen jedoch verschnitten werden, wenn diese nicht zuf\u00e4llig perfekt der Reihe nach aufgehen. Wer seine Quadratmetersumme vorliegen hat, der rechnet deshalb noch einmal 10 Prozent f\u00fcr Verschnitt und Reserve hinzu.<\/p>\n<h2>Kalibernummer und Brandfarbennummer<\/h2>\n<p>Zwei vielleicht unbekannte Begriffe, die aber f\u00fcr den Fliesenkauf wichtig sind. Die Kalibernummer und die Brandfarbennummer m\u00fcssen identisch sein, andernfalls kann es passieren, dass die Optik der Fliesen variiert. Die Kalibernummer beschreibt dabei die Gr\u00f6\u00dfe der einzelnen Fliesen. Bei der Brandfarbennummer geht es um die genau errechnete Farbnuance.<\/p>\n<h2>Qualit\u00e4tskennzeichnung beim Fliesenkauf<\/h2>\n<p>Jeder m\u00f6chte qualitativ hochwertige und einwandfreie Ware kaufen. Tats\u00e4chlich werden die Fliesen entsprechend gekennzeichnet. Dabei steht \u201e1 Ware\u201c nat\u00fcrlich f\u00fcr eben genannte Eigenschaften. Die Fliesen entsprechen s\u00e4mtlichen Normen und weisen keine optischen M\u00e4ngel auf. Die Rede ist von Glasurfehlstellen oder Glasurpickelchen. Auch auf Oberfl\u00e4cheneinschl\u00fcsse wurden diese Fliesen gepr\u00fcft. Die \u201e1 Wahl\u201c-Fliesen d\u00fcrfen maximal zu 5% kleine M\u00e4ngel aufweisen.<\/p>\n<p><strong>Mit diesen Informationen d\u00fcrfen Sie sich nun Ihre eigenen <a href=\"\/\">Fliesen kaufen<\/a> gehen. Sie wissen nun, dass Farbe und optische Besonderheiten nicht das Wichtigste beim Fliesenkauf sind, aber nat\u00fcrlich eine Frage des guten Geschmacks sind. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fliesen sind wieder voll im Trend. Aus diesem Grund lassen sich Hersteller aller Art auch einiges einfallen, um ihre Produkte m\u00f6glichst hochwertig herzustellen. Dies beginnt bei den Qualit\u00e4tsmerkmalen, geht weiter \u00fcber die Optik und Gr\u00f6\u00dfe und endet bei den speziellen Eigenschaften, die bei entsprechender Fliesenwahl entscheidend sind. Aufgrund der sich uns bietenden breiten Auswahl ist [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"7","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[7,31],"tags":[],"class_list":["post-2025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber","category-planung"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":6,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":3728,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2025\/revisions\/3728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/2030"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}