{"id":2619,"date":"2019-07-08T09:14:01","date_gmt":"2019-07-08T07:14:01","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=2619"},"modified":"2024-01-26T17:24:00","modified_gmt":"2024-01-26T16:24:00","slug":"so-entfernen-sie-kalk-auf-fliesen-und-armaturen","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/so-entfernen-sie-kalk-auf-fliesen-und-armaturen\/2019\/07","title":{"rendered":"So entfernen Sie Kalk auf Fliesen und Armaturen"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Kennen Sie das? Ihr Badezimmer ist gerade vor einigen Jahren neugestaltet worden und mittlerweile bildet sich an den Fliesen Kalk? Vor allem in der Dusche und rund um das Waschbecken kann der besonders hartn\u00e4ckig sein. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen und welche Mittel umweltschonend sind.<\/strong><\/p>\n<p>Wer in Regionen mit besonders hartem Wasser wohnt, kennt das leidige Problem: Trotz regelm\u00e4\u00dfiger Reinigung finden sich nach einiger Zeit Kalkablagerungen auf den Fliesen, an Wasserh\u00e4hnen oder Duschk\u00f6pfen. Erkennbar ist der Kalk an einem wei\u00dfen Schleier, der sich \u00fcber die Fliesen legt und in Zwischenr\u00e4ume kriecht. Vor allem auf dunkleren Fliesen st\u00f6rt dies die Optik im Bad erheblich. Die Krux am Kalk: Einmal getrocknet, l\u00e4sst sich der Kalk nicht mehr mit \u00fcblichen Reinigungsmitteln und Wasser entfernen. Weil sich das Wasser in Dusche, Waschbecken oder Bad immer an den gleichen Stellen sammelt, nehmen die Kalkablagerungen im Laufe der Zeit zu.<\/p>\n<h2>Wie entsteht Kalk?<\/h2>\n<div>\n<p>Kalk besteht aus Calciumcarbonat und ist im Erdreich \u00fcber viele Millionen Jahre durch tierische Ablagerungen entstanden. Je nachdem, in welcher Region Sie leben, schwankt der Kalkanteil im Boden. Wasser, das im Erdreich durch Kalkvorkommen flie\u00dft, enth\u00e4lt dann Spurenelemente. Unser Wasser wird in unseren Breitengraden in H\u00e4rtegrade eingeteilt: Man unterscheidet zwischen hartem, mittelhartem und weichem Wasser. Haushalte mit hartem Wasser haben besonders mit Kalkablagerungen zu k\u00e4mpfen. Tritt nun Wasser auf Fliesen, Waschbecken oder die Duschkabine, trocknet zwar das Wasser ab. Zur\u00fcckbleiben allerdings feinste Partikel an Kalk, die sich im Laufe der Zeit zu einem wei\u00dfen oder grauen Belag ausbilden. Die Gesundheit gef\u00e4hrden tut Kalk allerdings nicht.<\/p>\n<p><em>Tipp: Wer den H\u00e4rtegrad seines Wassers erfragen m\u00f6chte, ruft beim zust\u00e4ndigen Wasserwerk der Gemeinde an.<\/em><\/p>\n<\/div>\n<h2>Kalk auf Fliesen entfernen: So geht es!<\/h2>\n<div>\n<p>Der Handel bietet eine Vielzahl an Reinigungsmitteln, um Kalk zu beseitigen. Diese sind allerdings voller Chemie und nicht immer n\u00f6tig. Denn Kalk l\u00e4sst sich auch mit Haushaltsmitteln entfernen. Zum Beispiel mit Zitronens\u00e4ure: Die S\u00e4ure ist daf\u00fcr verantwortlich, dass sich die Kalkkrusten bei leichten und mittleren Verschmutzungen wieder aufl\u00f6sen. Dazu bilden Sie eine L\u00f6sung aus Zitronens\u00e4ure und warmem Wasser und geben diese auf die verschmutzten Fliesen. Einige Zeit einwirken lassen, mit klarem Wasser gut absp\u00fclen und einem Tuch trockenreiben. Wer starke Kalkablagerung auf den Fliesen hat, sollte die Anwendung regelm\u00e4\u00dfig wiederholen.<\/p>\n<p>Wer mit sehr starken Kalkablagerungen zu tun hat, kann sich auch mit Essig oder Essigessenz behelfen. Aber Achtung: Testen Sie, ob das Material s\u00e4urefest ist. Essig greift Oberfl\u00e4chen wie Marmor, Kunststoff oder Natursteine an. Diese sollten Sie in keinem Fall mit Essig behandeln. Auf <a href=\"https:\/\/www.franke-raumwert.de\/Fliesenwelten\/TW-Fliesen-fuers-Bad\/\" target=\"_blank\" rel=\"noopener\">Feinsteinzeugfliesen<\/a> testen Sie am besten in einer kleinen Ecke, wie diese auf Essig oder Essigessenz wirken. Ist alles unauff\u00e4llig, k\u00f6nnen Sie die Fliesen gro\u00dffl\u00e4chiger behandeln.<\/p>\n<p>Auch Kunststoffdichtungen m\u00f6gen keine s\u00e4urehaltigen Fl\u00fcssigkeiten. Diese Bereiche sollten Sie nach M\u00f6glichkeit aussparen. Ein Hinweis zu den Fugen: Bevor Sie mit der Reinigung der Fliesen beginnen, benetzen Sie Fliesen und vor allem Fugen mit ausreichend Wasser. Haben sich die Fugen mit Wasser vollgesogen, hat das Reinigungsmittel kaum eine Chance, in die Fugen vorzudringen und sie zu sch\u00e4digen.<\/p>\n<\/div>\n<h2>Duschk\u00f6pfe entkalken<\/h2>\n<div>\n<p>Um einen Duschkopf zu entkalken, gibt es eine besonders elegante Methode: Dazu wird der Duschkopf zun\u00e4chst abgeschraubt, um ihn danach in eine Sch\u00fcssel mit Wasser und einer L\u00f6sung aus 10 Prozent Zitronens\u00e4ure zu geben. Hier lassen Sie ihn 1,5 bis 2 Stunden einwirken. Danach herausnehmen, mit klarem Wasser gut absp\u00fclen, mit einem Lappen sauber wischen und in der Duschkabine montieren. Die S\u00e4ure sollte den Kalk zuverl\u00e4ssig aufgel\u00f6st haben.<\/p>\n<p>Wer seinen Duschkopf nicht abmontieren kann oder seinen Wasserhahn auf gleiche Art von Kalk befreien m\u00f6chte, bedient sich eines Luftballons, der ein wenig mit Zitronens\u00e4ure oder der Essigessenz-Wasser-L\u00f6sung gef\u00fcllt wird. Den Luftballon an der Armatur oder am Duschkopf mit einem Haushaltsgummi befestigen und ein bis zwei Stunden einwirken lassen.<\/p>\n<p>Kalk an den Glasw\u00e4nden der Duschkabine l\u00e4sst sich \u00fcbrigens ebenfalls mit einem weichen Tuch und etwas Essig oder einer Zitronens\u00e4ure-L\u00f6sung behandeln.\u00a0Ein letzter Hinweis zur Reinigung: Tragen Sie beim Reinigen mit S\u00e4uren immer gute Gummihandschuhe, damit die L\u00f6sung gar nicht erst mit Haut in Kontakt kommt. S\u00e4ure sollte ebenfalls niemals in die Augen gelangen.<\/p>\n<\/div>\n<h2>Kalk auf Fliesen und Armaturen vermeiden<\/h2>\n<div>\n<p>Wer in einer Region mit stark kalkhaltigem Wasser lebt, sollte besser vorbeugen als sich sp\u00e4ter \u00fcber Kalkablagerungen zu \u00e4rgern. Zum Beispiel in der Dusche: Nachdem Sie geduscht haben, sollten Sie restliches Wasser auf Fliesen, an der Duschkabine oder auf dem Boden mit einem Wischgummi beseitigen. F\u00fcr Armaturen eigenen sich weiche Mikrofasert\u00fccher oder ein Leder, um das Wasser streifenfrei aufzunehmen.<\/p>\n<p>Platzieren Sie am besten in der Duschkabine einen kleinen Abzieher, wie wir ihn vom Fenster putzen kennen. Auf diese Weise haben wir unser Werkzeug sofort griffbereit, wenn wir mit dem Duschen fertig sind. Im Handel finden sich mittlerweile zahlreiche Modelle, die tolle Designs mitbringen. Im Waschtischunterschrank k\u00f6nnten Sie einen Lappen oder ein Leder unterbringen, um Armaturen zu trocknen.<\/p>\n<p>Sie haben Lust auf weitere Haushaltstipps? In unserem Artikel \u201e<a href=\"https:\/\/www.franke-raumwert.de\/aktuelles\/die-10-besten-tipps-zum-fliesen-reinigen\/2016\/11\" target=\"_blank\" rel=\"noopener\">Die 10 besten Tipps zum Fliesen reinigen<\/a>\u201c finden Sie noch mehr Tipps, um Kalk, Schmutz oder verf\u00e4rbten Fugen zu Leibe zu r\u00fccken!<\/p>\n<\/div>\n<div style=\"text-align: right;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Kennen Sie das? Ihr Badezimmer ist gerade vor einigen Jahren neugestaltet worden und mittlerweile bildet sich an den Fliesen Kalk? Vor allem in der Dusche und rund um das Waschbecken kann der besonders hartn\u00e4ckig sein. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen und welche Mittel umweltschonend sind. Wer in Regionen mit besonders hartem Wasser [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"7","_seopress_titles_title":"Kalk auf Fliesen und Armaturen entfernen - Franke Raumwert","_seopress_titles_desc":"Ihr Badezimmer ist gerade neu gestaltet und schon bildet sich an den Fliesen Kalk? Wir erkl\u00e4ren, wie Sie umweltschonend dagegen vorgehen.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Kalk auf Fliesen","footnotes":""},"categories":[7,19],"tags":[],"class_list":["post-2619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber","category-sanitaer"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":15,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"predecessor-version":[{"id":5651,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2619\/revisions\/5651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/5146"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}