{"id":2744,"date":"2019-08-30T16:24:54","date_gmt":"2019-08-30T14:24:54","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=2744"},"modified":"2024-01-26T16:18:07","modified_gmt":"2024-01-26T15:18:07","slug":"rektifizierte-fliesen-was-bedeutet-das-eigentlich","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/rektifizierte-fliesen-was-bedeutet-das-eigentlich\/2019\/08","title":{"rendered":"Rektifizierte Fliesen: Was bedeutet das eigentlich?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Sie stehen vor der Renovierung eines Wohnraums wie Bad, K\u00fcche oder Terrasse? Sp\u00e4testen dann, wenn sich Bauherren mit dem Thema Fliesenkauf besch\u00e4ftigen, stolpern viele \u00fcber den Begriff der rektifizierten Kanten. Was dahinter steckt, erkl\u00e4ren wir in unserem heutigen Beitrag.<\/strong><\/p>\n<p>Sicher ist Ihnen schon einmal aufgefallen, dass mit Fliesen verkleidete B\u00f6den und Wandfl\u00e4chen ein sehr unterschiedliches Fugenbild haben k\u00f6nnen. Manche Fl\u00e4chen wirken beinahe wie eine geschlossene Fl\u00e4che, auf anderen Fl\u00e4chen lassen sich Fugen gut erkennen und geh\u00f6ren offensichtlich zur Optik dazu. In manchen F\u00e4llen ist das durchaus erw\u00fcnscht, zum Beispiel bei Natursteinb\u00f6den, mit denen Bauherren ein besonders rustikales Ambiente erzeugen m\u00f6chten. Moderne Fliesenwelten setzen allerdings eher auf minimalistisch gestaltete Fugen, die nur wenige Millimeter breit sind. Um dies umzusetzen, kommen rektifizierte Fliesen zum Einsatz. Auch in unserem <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/\" target=\"_blank\" rel=\"noopener\">Fliesenshop<\/a> werden sie bei zahlreichen Fliesen den Begriff &#8222;rektifizierte Kanten&#8220; finden.<\/p>\n<h2>Rektifizierte Fliesen sorgen f\u00fcr ein schmales Fugenbild<\/h2>\n<p>Fliesenhersteller bem\u00fchen sich heute, Fliesen mit exakt zugeschnittenen Ma\u00dfen und Kanten zu produzieren. Denn sie sind der Garant f\u00fcr ein minimalistisch gestaltetes Fugenbild, das heute in zeitgen\u00f6ssischen Bauprojekten vielfach gew\u00fcnscht wird. Doch gerade die Herstellung der Feinsteinzeugfliesen ist kaum vorhersehbar. Beim eigentlich Brennvorgang wird der Rohstoff Keramik unter hohem Druck gepresst und sp\u00e4ter bei einer Temperatur von bis zu 1300 Grad gebrannt. Dann entstehen minimale Ma\u00dfunterschiede, die sich auf das sp\u00e4tere Fliesenbild negativ auswirken k\u00f6nnten. Nach dem Brennvorgang werden viele Feinsteinzeugfliesen deswegen auf ein zuvor definiertes Fertigungsma\u00df geschnitten und kalibriert. Rektifiziert sind sie dann, wenn die Kanten auf exakte 90-Grad-Winkel zugeschliffen werden. Ein besonders schmales Fugenbild von 1,5 mm bis 2 mm Breite ist nun m\u00f6glich und damit eine besonders ruhige Fliesenoberfl\u00e4che im Wohnraum.<\/p>\n<h2>Warum kann eine rektifizierte Kante wichtig sein?<\/h2>\n<p>Fugenbilder habe heute eine wichtige Funktion in der Wand- und Bodengestaltung. Denn gerade in modernen Wohnkonzepten wird ein einheitliches und besonders ruhiges Fugenbild gew\u00fcnscht. Das erreicht man zum Beispiel, indem man besonders gro\u00dfe Platten verwendet, die ohne Versatz verlegt werden. Die rektifizierten Kanten sorgen daf\u00fcr, dass Fliesen gleich gro\u00df sind und der Handwerker auf diese Weise die Fliesen auch bei einer sehr schmalen Fuge exakt verlegen kann.<\/p>\n<p>Wer sich dagegen eine rustikales Bodengestaltung, zum Beispiel mit Naturstein w\u00fcnscht, braucht auf eine Kalibrierung nicht zu achten. Hier ist das Fugenbild meistens breiter und Fliesentoleranzen k\u00f6nnen ausgeglichen werden.<\/p>\n<figure id=\"attachment_2750\" aria-describedby=\"caption-attachment-2750\" style=\"width: 562px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2750\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/08\/FLAVIKER-Hangar.jpg\" alt=\"FLAVIKER-Hangar Terrassenplatte\" width=\"562\" height=\"805\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/08\/FLAVIKER-Hangar.jpg 621w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/08\/FLAVIKER-Hangar-209x300.jpg 209w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/08\/FLAVIKER-Hangar-293x420.jpg 293w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/><figcaption id=\"caption-attachment-2750\" class=\"wp-caption-text\">Auch im Au\u00dfenbereich sind rektifizierte Fliesen mittlerweile ohne Probleme zu verlegen. Das Foto zeigt die Terrassenplatte HANGAR des Herstellers FLAVIKER.\u00a0Foto: Herstellerbild<\/figcaption><\/figure>\n<h2>Lassen sich Fliesen komplett ohne Fuge verlegen?<\/h2>\n<p>Fugen dienen nicht nur der Optik, sondern haben auch eine wichtige Funktion: Sie fangen verschiedene Spannungszust\u00e4nde auf, zum Beispiel Temperaturschwankungen im Sommer und Winter oder eine m\u00f6gliche Baurestfeuchte beim Neubau. Auch die thermischen Spannungen zwischen Untergrund, Fliesenkleber und Belag werden durch das Fugenbild aufgefangen. Daher sollten Fliesen nicht ohne Fugen verlegt werden. Doch durch Fliesen mit kalibrierten Kanten und der passenden Fugenfarbe entstehen Fl\u00e4chen, die einer geschlossenen Bodenfl\u00e4che sehr \u00e4hnlich sind.<\/p>\n<h2>Wie erkenne ich beim Kauf, ob Fliese rektifiziert ist?<\/h2>\n<p><img decoding=\"async\" class=\"wp-image-2749 size-thumbnail alignleft\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/08\/Rekrifizerte-Kanten-150x66.jpg\" alt=\"Kalibrierte oder rektifizierte Kanten\" width=\"150\" height=\"66\" \/>Ob eine Fliese \u00fcber rektifizierte Kanten verf\u00fcgt, finden Sie in vielen F\u00e4llen in der Produktinformation zu jeder Fliese. In unserem <a href=\"https:\/\/www.franke-raumwert.de\/\" target=\"_blank\" rel=\"noopener\">Shop<\/a> finden Sie beispielsweise den Hinweis f\u00fcr eine rektifizierte Fliese in einem der Symbole direkt rechts neben der Fliese. Das soll Ihnen helfen, sich schnell im gro\u00dfen Angebot der Fliesen zurechtzufinden.<\/p>\n<p style=\"text-align: right;\"><em>Titelbild: Herstellerfoto<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sie stehen vor der Renovierung eines Wohnraums wie Bad, K\u00fcche oder Terrasse? Sp\u00e4testen dann, wenn sich Bauherren mit dem Thema Fliesenkauf besch\u00e4ftigen, stolpern viele \u00fcber den Begriff der rektifizierten Kanten. Was dahinter steckt, erkl\u00e4ren wir in unserem heutigen Beitrag. Sicher ist Ihnen schon einmal aufgefallen, dass mit Fliesen verkleidete B\u00f6den und Wandfl\u00e4chen ein sehr [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"Beim Fliesenkauf stolpern Sie \u00fcber den Begriff der rektifizierten Kanten? Was dahinter steckt, erkl\u00e4ren wir in unserem Beitrag.","_seopress_robots_index":"","_seopress_analysis_target_kw":"rektifizierte Fliesen","footnotes":""},"categories":[7],"tags":[],"class_list":["post-2744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=2744"}],"version-history":[{"count":9,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2744\/revisions"}],"predecessor-version":[{"id":6110,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/2744\/revisions\/6110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/2747"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=2744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=2744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=2744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}