{"id":3076,"date":"2020-02-10T11:56:55","date_gmt":"2020-02-10T10:56:55","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=3076"},"modified":"2023-12-06T14:45:27","modified_gmt":"2023-12-06T13:45:27","slug":"rau-maskulin-und-charmant-einrichten-im-industrial-design","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/rau-maskulin-und-charmant-einrichten-im-industrial-design\/2020\/02","title":{"rendered":"Rau, maskulin und charmant: Einrichten im Industrial Design"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Seinen Ursprung hat er in den Szenecaf\u00e9s und K\u00fcnstlerlofts New Yorks, l\u00e4ngst ist er aber in private Wohnr\u00e4ume eingezogen: der Industrial Style, der uns mitten ins Gro\u00dfstadt-Leben zu katapultieren scheint. Seinen k\u00fchlen, aber gem\u00fctlichen Charme gewinnt er durch die Gestaltung mit alten Materialien. Wir zeigen Ihnen, wie Sie Ihre Wohnung im Industrial Style in Szene setzen.<\/strong><\/p>\n<h2>Industrial Design: Charme alter Lagerhallen<\/h2>\n<p>M\u00f6bel und Materialien, die einst in alten Fabriken und Lagerhallen ihr Zuhause hatten, d\u00fcrfen im industriellen Stil bei Ihnen einziehen.\u00a0 Dabei m\u00fcssen die M\u00f6bel und Accessoires nicht neu sein, sondern vor allem funktionalen Charakter haben \u2013 und eine Geschichte erz\u00e4hlen. H\u00e4ufig finden sich Kontraste zwischen neu und alt oder schlicht und luxuri\u00f6s. Lampen vom Flohmarkt neben Designersofas, rostige Fahrr\u00e4der neben Luxusk\u00fcchen \u2013 all das ist m\u00f6glich. Und auch, wenn Sie nicht \u00fcber ein gro\u00dfz\u00fcgiges Loft verf\u00fcgen, k\u00f6nnen Sie mit ein paar Tricks das gro\u00dfst\u00e4dtische Industrie-Flair in Ihre vier W\u00e4nde zaubern.<\/p>\n<h2>Accessoires im industriellen Design<\/h2>\n<p>Schon Kleinigkeiten unterstreichen den rauen Charme, die den industriellen Stil ausmachen. Beliebt sind zum Beispiel vergilbte Ziffernbl\u00e4tter, alte Blechschilder und Retro-Reklame. Dekorative Zeitzeugen k\u00f6nnen St\u00fchle mit rostigen Beinen sein, Spinde stillgelegter Fabrikanlagen und Schr\u00e4nke mit Patina. Auf Flohm\u00e4rkten und in Internet-Aktionen finden Sie allerlei stilsicheres Zubeh\u00f6r. Und selbst, wenn Sie keinen Zugang zu alten Originalen haben, m\u00fcssen Sie nicht auf diesen markanten Stil verzichten. Auch selbstgemachte Accessoires, wie nackte Gl\u00fchbirnen an der Decke oder eine Metalllampe aus unbehandeltem Holz erzielen die gew\u00fcnschte Wirkung. Nat\u00fcrlich k\u00f6nnen Sie auch im M\u00f6belhaus und in Online- Shops f\u00fcndig werden: Viele Hersteller bieten M\u00f6bel und Accessoires im Industrial Design an.<\/p>\n<h2>Industrial Design kann auch gem\u00fctlich sein<\/h2>\n<p>Die Grundfarben im industriell gepr\u00e4gten Einrichtungsstil sind Schwarz, Wei\u00df, Grau und Braun; die Materialien bestehen aus schwerem Messing, Stahl und Massivholz. Aber einzelne Farbakzente und weiche Textilien bilden einen spannungsreichen Kontrast und sorgen dennoch f\u00fcr Gem\u00fctlichkeit. Flauschige Deko-Kissen auf coolen Ledersofas, gro\u00dfe Polstersessel in leuchtenden Farben und transparente Vorh\u00e4nge lockern die dunklen Grundfarben auf und wirken den schweren Materialien mit Luftigkeit und Farbenfreude entgegen.<\/p>\n<h2>Industrial Style \u2013 schick, cool und gem\u00fctlich<\/h2>\n<p>Angelehnt an gro\u00dfst\u00e4dtische K\u00fcnstlerlofts wird gerne eine offene Wohnkultur mit hohen Decken und gro\u00dfen Glasfl\u00e4chen geschaffen. Fliesen in <a href=\"https:\/\/www.franke-raumwert.de\/Fliesenwelten\/fliesen-in-metalloptik\/\">Metall<\/a>&#8211; oder <a href=\"https:\/\/www.franke-raumwert.de\/Fliesenwelten\/TW-Betonoptik\/\">Betonoptik<\/a> schaffen im Handumdrehen eine elegante Atmosph\u00e4re. Die gro\u00dffl\u00e4chige Fliesenkollektion, wie zum Beispiel \u201e<a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Keraben\/Boreal\/\">Boreal<\/a>\u201c des Herstellers Keraben in Beige, Schwarz, Wei\u00df und Grau, oder die Fliesenserie \u201e<a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/pc-hemiplus\/\">HemiPlus<\/a>\u201c von PrimeCollection in Braun- und Graut\u00f6nen wirken durch ihr ebenm\u00e4\u00dfiges Fugenbild besonders glatt &#8211; und vergr\u00f6\u00dfern den Wohnraum optisch. Freiliegende Stahltr\u00e4ger oder <a href=\"https:\/\/www.franke-raumwert.de\/Keraben-Wall-Brick-Old-Cotto-KKHPG02O.html\">Backsteinfliesen<\/a> an den W\u00e4nden unterst\u00fctzen das industrielle Design wirkungsvoll.<\/p>\n<p>Auch im Badezimmer sind gro\u00dfformatige Wand- und Bodenfliesen im <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/matplus-neuheit\/\">Beton<\/a>&#8211; oder <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Tau-Ceramica\/Tau-Ceramica-Metallica-Corten\/\">Metalllook<\/a> das A und O. Auch der Badunterschrank sowie Regale aus Beton- oder Metall unterstreichen den industriellen Stil effektvoll. Im Schlafzimmer hingegen sollte der Industrie-Look mit Vorsicht umgesetzt werden, damit es nicht zu d\u00fcster wirkt. Tagesdecken aus kuscheligen Materialien, St\u00fchle aus Rattan und Kissen in Ihren Lieblingsfarben sorgen f\u00fcr eine wohlig-warme Atmosph\u00e4re trotz <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/timeline\/\">Beton<\/a> und <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Flaviker\/rebel\/\">Metall<\/a> an W\u00e4nden und B\u00f6den.<\/p>\n<figure id=\"attachment_3084\" aria-describedby=\"caption-attachment-3084\" style=\"width: 900px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Flaviker\/Dakota\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3084 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product.jpg\" alt=\"Flaviker Dakota Franke Raumwert\" width=\"900\" height=\"659\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product.jpg 900w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product-300x220.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product-768x562.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product-80x60.jpg 80w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product-696x510.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/02\/275222_Product-574x420.jpg 574w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-3084\" class=\"wp-caption-text\">Fliesenserie Dakota von Flaviker. Foto: Franke<\/figcaption><\/figure>\n<h2>Upcycling: aus alt mach neu<\/h2>\n<p>Das Industrial Design liebt das Upcycling: Bereits genutzte Gegenst\u00e4nde oder M\u00f6bel werden so aufgearbeitet, dass sie eine Art zweites Leben erhalten. Authentische Accessoires lasen sich dann mit neuen Gegenst\u00e4nden kombinieren. Im Vordergrund stehen auch hier schn\u00f6rkelloses Design und Funktionalit\u00e4t. Wer auf der Suche nach Ideen ist, st\u00f6bert zum Beispiel auf der Kreativ-Plattform Pinterest.<\/p>\n<p>Viel Spa\u00df beim Einrichten!<\/p>\n<p style=\"text-align: right;\"><em>Coverfoto:\u00a0<a href=\"https:\/\/unsplash.com\/@aahubs?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Aaron Huber<\/a>\u00a0on\u00a0<a href=\"https:\/\/unsplash.com\/s\/photos\/loft?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Unsplash<\/a><\/em><\/p>\n<div class=\"shariff\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Frau-maskulin-und-charmant-einrichten-im-industrial-design%2F2020%2F02\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Frau-maskulin-und-charmant-einrichten-im-industrial-design%2F2020%2F02&text=Rau%2C%20maskulin%20und%20charmant%3A%20Einrichten%20im%20Industrial%20Design\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Frau-maskulin-und-charmant-einrichten-im-industrial-design%2F2020%2F02&media=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fwp-content%2Fuploads%2F2020%2F02%2Faaron-huber-s95oB2n9jng-unsplash.jpg&description=Rau%2C%20maskulin%20und%20charmant%3A%20Einrichten%20im%20Industrial%20Design\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span class=\"shariff-text\">merken<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Seinen Ursprung hat er in den Szenecaf\u00e9s und K\u00fcnstlerlofts New Yorks, l\u00e4ngst ist er aber in private Wohnr\u00e4ume eingezogen: der Industrial Style, der uns mitten ins Gro\u00dfstadt-Leben zu katapultieren scheint. Seinen k\u00fchlen, aber gem\u00fctlichen Charme gewinnt er durch die Gestaltung mit alten Materialien. Wir zeigen Ihnen, wie Sie Ihre Wohnung im Industrial Style in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"3","_seopress_titles_title":"","_seopress_titles_desc":"Wir stellen Ihnen die M\u00f6glichkeiten vor, wie Sie Ihre Wohnung im Industrial Style in Szene setzen \u2013 und sich rundum wohlf\u00fchlen k\u00f6nnen!","_seopress_robots_index":"","_seopress_analysis_target_kw":"Industrial Design","footnotes":""},"categories":[3],"tags":[],"class_list":["post-3076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wohnideen"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=3076"}],"version-history":[{"count":9,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3076\/revisions"}],"predecessor-version":[{"id":6135,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3076\/revisions\/6135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/3082"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=3076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=3076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=3076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}