{"id":3265,"date":"2020-05-28T10:29:01","date_gmt":"2020-05-28T08:29:01","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=3265"},"modified":"2024-05-13T11:03:23","modified_gmt":"2024-05-13T09:03:23","slug":"grossformatfliesen-wir-beantworten-ihre-wichtigsten-fragen","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/grossformatfliesen-wir-beantworten-ihre-wichtigsten-fragen\/2020\/05","title":{"rendered":"Gro\u00dfformatfliesen: Wir beantworten Ihre wichtigsten Fragen!"},"content":{"rendered":"<p><strong><br \/>\nGro\u00dfformatfliesen liegen im Trend und werden heute immer h\u00e4ufiger in Bad, K\u00fcche oder Wohnraum verbaut. Sie schaffen einheitliche Fl\u00e4chen und lassen auch kleine R\u00e4ume gro\u00df wirken! Ma\u00dfe von 1,20 x 1,20 Meter oder 1 x 3 Meter sind keine Seltenheit mehr. Aber sind sie auch f\u00fcr jeden Raum geeignet? Und welche Kosten kommen auf mich zu? Diese und noch mehr Fragen beantworten wir heute.<\/strong><\/p>\n<h2>Wie gro\u00df ist eigentlich eine Gro\u00dfformatfliese?<\/h2>\n<p>Gro\u00dfformatfliesen beginnen typischerweise bei einer Kantenl\u00e4nge von 60 Zentimetern. Aber es geht nat\u00fcrlich heute viel gr\u00f6\u00dfer: 1,20 x 1,20 Meter oder 1 x 3 Meter sind keine Seltenheit mehr.<\/p>\n<h2>Aus welchem Material bestehen Gro\u00dfformatfliesen?<\/h2>\n<p>Gro\u00dfformatfliesen sind h\u00e4ufig aus Feinsteinzeug hergestellt. Feinsteinzeug wird mit sehr hoher Brenntemperatur hergestellt und wird so besonders widerstandsf\u00e4hig. Die Fliesen kommen gut mit Hitze und Frost klar, sind wasserundurchl\u00e4ssig, sehr bruchfest und pflegleicht. Selbst f\u00fcr vielgenutzte Treppen und Flure oder Ladengesch\u00e4fte und B\u00fcros ist Feinsteinzeug gut geeignet.<\/p>\n<p>In ihrem Aussehen sind Gro\u00dfformatfliesen besonders vielf\u00e4ltig. Die heutigen Produktionstechniken sorgen daf\u00fcr, dass ihre Oberfl\u00e4chen wie Holz, Metall, Stein oder Beton aussehen k\u00f6nnen. Haptik \u00fcbrigens inklusive!<\/p>\n<h2>Wo kann ich Gro\u00dfformat-Fliesen \u00fcberall verlegen lassen?<\/h2>\n<p>Gro\u00dfformatfliesen sind \u00e4u\u00dferst vielseitig. Sie schm\u00fccken B\u00f6den und W\u00e4nde im Wohnzimmer, K\u00fcche, im Bad oder im Flur. Sie kommen als Terrassenplatten aber ebenso auf dem Balkon, der Terrasse oder Gehwegplatten zum Einsatz. Viele Kollektionen haben sowohl Modelle f\u00fcr Innenr\u00e4ume wie den Outdoorbereich im Portfolio. Das erm\u00f6glicht einen flie\u00dfenden \u00dcbergang zwischen drinnen und drau\u00dfen und vergr\u00f6\u00dfert den Wohnraum im Sommer optisch. Gro\u00dfformatfliesen sind robust, pflegeleicht und langlebig. Daher k\u00f6nnen sie auch auf stark beanspruchten B\u00f6den verlegt werden und k\u00f6nnen N\u00e4sse, Regen oder Frost vertragen.<\/p>\n<figure id=\"attachment_3270\" aria-describedby=\"caption-attachment-3270\" style=\"width: 571px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3270\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002-768x1024.jpg\" alt=\"Gro\u00dfformatfliesen\" width=\"571\" height=\"761\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002-768x1024.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002-225x300.jpg 225w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002-696x928.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002-315x420.jpg 315w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/IMG_9512-002.jpg 1000w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/><figcaption id=\"caption-attachment-3270\" class=\"wp-caption-text\">Zum Verlegen von Fliesen im Gro\u00dfformat ben\u00f6tigt man fachliches Knowhow und Fingerspitzengef\u00fchl. Die Mitarbeiter unserer Firma haben beides. Foto: Franke<\/figcaption><\/figure>\n<h2>Kleine R\u00e4ume, gro\u00dfe Fliesen: Geht das wirklich?<\/h2>\n<p>Ja, das geht! Nat\u00fcrlich vergr\u00f6\u00dfern Gro\u00dfformatfliesen den Raum nicht wirklich. Die ruhige Erscheinung allerdings, die mit dem reduzierten Fugenbild einhergeht, sorgt daf\u00fcr, dass auch ein kleiner Raum gr\u00f6\u00dfer wahrgenommen wird. Besonders viel Gr\u00f6\u00dfe schummeln Sie \u00fcbrigens in den Raum, wenn Sie eine Gro\u00dfformatfliese mit besonders ruhiger Oberfl\u00e4che und einem hellen Ton w\u00e4hlen. Achten Sie auch auf die Verlegart, die bei Fliesen sehr unterschiedlich sein kann. Je gradliniger sie ist, umso ruhiger wirkt die Oberfl\u00e4che.<\/p>\n<p>Beachten sie auch: Je nach Raumma\u00df haben Sie nat\u00fcrlich auch immer Verschnitt beim Verlegen der Fliesen. Das bleibt auch bei den Gro\u00dfformatfliesen in kleinen R\u00e4umen nicht aus. Insofern gilt: Vorher zun\u00e4chst gr\u00fcndlich planen, dann bestellen.<\/p>\n<h2>Lassen sich Gro\u00dfformatfliesen nur auf dem Fu\u00dfboden oder auch an der Wand verlegen?<\/h2>\n<p>Fliesen im XXL-Format lassen sich sowohl auf dem Fu\u00dfboden als auch an der Wand verlegen. Achten Sie am besten auf die Herstellerangaben. Entscheidend dabei: Sie ben\u00f6tigen in beiden F\u00e4llen einen sehr glatten Untergrund, um die gro\u00dfen Fliesen zu verlegen, sowie einen festen Verbund. H\u00e4ufig ist eine Ausgleichsspachtelung des Untergrunds n\u00f6tig. Manchmal reicht der Klebem\u00f6rtel, in anderen F\u00e4llen muss Reparaturm\u00f6rtel her.<\/p>\n<p>Warum ist das so? Jede Fliese hat Toleranzen, ohne gleich fehlerhaft zu sein. Solche Toleranzen zwischen dem Mittelpunkt der Fliese bis zur Ecke werden gr\u00f6\u00dfer, je gro\u00dfformatiger die Fliese ist. Trotzdem muss sie mit der gesamten Fl\u00e4che fest mit dem Untergrund verbunden sein. Sonst besteht die Gefahr, dass die Fliese bricht. Faktisch bedeutet dies: <a href=\"https:\/\/www.franke-raumwert.de\/Zubehoer\/Ausgleichsmassen\/Selbstnivellierende-Bodenausgleichsmassen\/\" target=\"_blank\" rel=\"noopener\">deutlich mehr M\u00f6rtel als bei kleineren Fliesen<\/a>. Ein stark saugender Untergrund muss vor der Verlegung zus\u00e4tzlich immer grundiert werden. Saugn\u00e4pfe helfen, die Platte perfekt zu positionieren.<\/p>\n<p>In der Regel wird der Kleber \u00fcbrigens im sogenannten Buttering-Floating-Verfahren aufgetragen. Ein Verfahren, bei dem sowohl auf der R\u00fcckseite der Fliese als auch an der Wand oder dem Boden Kleber aufgetragen und gek\u00e4mmt wird. So entsteht eine vollfl\u00e4chige Auftragung des Klebers.<\/p>\n<p><em>Tipp: Achten Sie beim Kauf der Gro\u00dfformatfliese auf den Begriff &#8222;<a href=\"https:\/\/www.franke-raumwert.de\/aktuelles\/rektifizierte-fliesen-was-bedeutet-das-eigentlich\/2019\/08\" target=\"_blank\" rel=\"noopener\">rektifizierte Kanten<\/a>&#8222;. Es bedeutet, dass die Kanten nach dem Brennvorgang gerade geschliffen wurden. So lassen sich auch beim Gro\u00dfformat m\u00f6glichst schmale Fugen verwirklichen. Ton-in-Ton-Fugenfarben unterst\u00fctzen den einheitlichen Look. <\/em><\/p>\n<h2>Gro\u00dfe Platten, schmale Fugen: Wie schmal darf es eigentlich sein?<\/h2>\n<p>Zu gro\u00dfformatige Fliesen geh\u00f6rt ein sch\u00f6nes Fugenbild. Besonders schmal sollte es am besten dazu sein, damit es optisch fast verschwindet. Die Fugenbreite von drei Millimetern sollen allerdings nicht unterschritten werden. Wir empfehlen Ihnen, die genaue Fugenbreite mit Ihrem Fliesenleger zu besprechen. Er kann die optimale Fugenbreite anhand der Herstellerdaten und Formatgr\u00f6\u00dfe errechnen. Manchmal ist in den Herstellerangaben die beste Fugenbreite bereits erw\u00e4hnt.<\/p>\n<figure id=\"attachment_3271\" aria-describedby=\"caption-attachment-3271\" style=\"width: 900px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.franke-raumwert.de\/flaviker-rebel-boden-und-wandfliese-white-60x120-cm.html\"><img decoding=\"async\" class=\"wp-image-3271 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel.jpg\" alt=\"Gro\u00dfformatfliese FLAVIKER Rebel\" width=\"900\" height=\"664\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel.jpg 900w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel-300x221.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel-768x567.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel-80x60.jpg 80w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel-696x513.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/FLAVIKER-Rebel-569x420.jpg 569w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-3271\" class=\"wp-caption-text\">Die Gro\u00dfformatfliese FLAVIKER Rebel ist in l\u00e4nglichen und quadratischen Formaten bis zu 60 x 120 cm und 120 x 120 cm erh\u00e4ltlich.\u00a0Foto: Herstellerbild<\/figcaption><\/figure>\n<h2>Was sollte man beim Verlegen einer Gro\u00dfformatfliese noch beachten?<\/h2>\n<p>Das Verlegen der Gro\u00dfformatfliese ben\u00f6tigt handwerkliches Geschick. Sofern sie nicht vom Fach sind, sollten Sie das Verlegen deswegen fachlich geschultem Personal \u00fcberlassen. Das zahlt sich am Ende aus. Einige Beispiel daf\u00fcr:<\/p>\n<p>Je gr\u00f6\u00dfer eine Fliese umso h\u00f6her das Gewicht. Das macht sich bei Gro\u00dfformatfliesen bemerkbar. Zwei Personen werden ben\u00f6tigt, um die Fliese zu bewegen oder zu verlegen. Das bedeutet am Ende h\u00f6here Kosten bei der Verlegung. Immer mehr Hersteller reagieren allerdings auf diesen Nachteil und entwickeln XXL-Fliesen mit nur 3-4 Millimetern St\u00e4rke. Das bedeutet allerdings auch eine m\u00f6gliche Bruchgefahr bei Transport oder Verarbeitung.<\/p>\n<h2>Was kosten Gro\u00dfformatfliesen?<\/h2>\n<p>XXL-Fliesen sind in allen erdenklichen Farben, Formaten und Stilwelten erh\u00e4ltlich. Zahlreiche Hersteller bieten ihre eigenen Kollektionen an. Pauschal l\u00e4sst sich ein Preis deswegen nicht benennen. Als Faustregel gilt: Nicht die Fliesen selbst schlagen mit h\u00f6heren kosten zu Buche, sondern die dazugeh\u00f6rige Verarbeitung durch den Fachbetrieb. Das ist ein Luxus \u2013 den Sie allerdings nicht bereuen werden! Sprechen Sie uns gerne an und wir geben Auskunft \u00fcber Vorgehensweise und Kosten.<\/p>\n<p><strong>Gro\u00df, gr\u00f6\u00dfer, am gr\u00f6\u00dften: Gro\u00dfformatfliesen sind an Eleganz und Design kaum zu \u00fcberbieten. Ob Holz, Beton oder Stein \u2013 auf dem Markt finden Sie sicher Ihre eigene Traumfliese. Um Ihnen die Suche im Angebot zu erleichtern, haben wir im Shop eine <a href=\"https:\/\/www.franke-raumwert.de\/Fliesenwelten\/TW-XXL---Fliesen\/\" target=\"_blank\" rel=\"noopener\">eigene Rubrik &#8222;XXL-FLiesen&#8220;<\/a> bereitgestellt. Wir w\u00fcnschen Ihnen viel Spa\u00df beim St\u00f6bern.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3273\" aria-describedby=\"caption-attachment-3273\" style=\"width: 522px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/alchimia\/\"><img decoding=\"async\" class=\"wp-image-3273\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/Prime-Collection-Alchimia.jpg\" alt=\"Prime-Collection-Alchimia\" width=\"522\" height=\"652\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/Prime-Collection-Alchimia.jpg 721w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/Prime-Collection-Alchimia-240x300.jpg 240w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/Prime-Collection-Alchimia-696x869.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2020\/05\/Prime-Collection-Alchimia-336x420.jpg 336w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><\/a><figcaption id=\"caption-attachment-3273\" class=\"wp-caption-text\">Die Gro\u00dfformatfliese Alchimia von PrimeCollection gibt es in Beige, Grau- und Braunt\u00f6nen.\u00a0Foto: Herstellerbild<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfformatfliesen liegen im Trend und werden heute immer h\u00e4ufiger in Bad, K\u00fcche oder Wohnraum verbaut. Sie schaffen einheitliche Fl\u00e4chen und lassen auch kleine R\u00e4ume gro\u00df wirken! Ma\u00dfe von 1,20 x 1,20 Meter oder 1 x 3 Meter sind keine Seltenheit mehr. Aber sind sie auch f\u00fcr jeden Raum geeignet? Und welche Kosten kommen auf mich [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"7","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"Gro\u00dfformatfliesen","footnotes":""},"categories":[7],"tags":[],"class_list":["post-3265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=3265"}],"version-history":[{"count":9,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3265\/revisions"}],"predecessor-version":[{"id":6495,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/3265\/revisions\/6495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/3268"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=3265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=3265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=3265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}