{"id":4881,"date":"2022-05-16T10:33:13","date_gmt":"2022-05-16T08:33:13","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=4881"},"modified":"2024-01-26T16:34:33","modified_gmt":"2024-01-26T15:34:33","slug":"mit-farbe-einrichten-bunte-fliesen-fuer-ihr-zuhause","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/mit-farbe-einrichten-bunte-fliesen-fuer-ihr-zuhause\/2022\/05","title":{"rendered":"Mit Farbe einrichten: Bunte Fliesen f\u00fcr Ihr Zuhause"},"content":{"rendered":"<p><strong><br \/>\nBringen Sie Farbe in Ihre Wohnung! Keramische Fliesen bieten vielf\u00e4ltige Farben und Muster, welche die Einrichtung pr\u00e4gen und zur Raumwirkung beitragen. Wir zeigen Ihnen, welche Farben in der Innenraumgestaltung im Trend liegen und welche Fliesen f\u00fcr Farbtupfer sorgen.<\/strong><\/p>\n<h2>Welche Farben sind modern?<\/h2>\n<p>Eine Frage, die sich nur schwer beantworten l\u00e4sst. Schlie\u00dflich weichen die j\u00e4hrlichen Farbtrends teils stark voneinander ab. Moderne Farben sind Farbt\u00f6ne oder Farbfamilien, die viele Jahre \u00fcberdauern. Ungebrochen sind Farben in <strong>nat\u00fcrlichen T\u00f6nen<\/strong> und <strong>Pastellfarben<\/strong>. Dank ihrer zur\u00fcckhaltenden und leichten Wirkung lassen sie sich gut kombinieren, \u00fcberzeugen aber auch als monochrome Varianten.<\/p>\n<p>Bei der Inneneinrichtung setzen sich ebenfalls <strong>Blau- und Gr\u00fcnt\u00f6ne<\/strong> seit vielen Jahren immer wieder durch. Die Nachfrage ist hoch. Das liegt unter anderem daran, dass Blau von vielen Menschen gemocht wird, weil es eine beruhigende Wirkung hat. Auch die Sehnsucht nach Meer und Freiheit (Himmel) liegt in diesem Farbspektrum.<\/p>\n<p>Wie sollen Sie nun mit Farbtrends umgehen? Trends kommen und gehen. Wirklich nachhaltige Trends \u00fcberdauern viele Jahre und pr\u00e4gen ganze Jahrzehnte. Sie m\u00fcssen nicht jedes Jahr Ihre Fliesenbel\u00e4ge und Wandfarben \u00e4ndern. Achten Sie jedoch darauf, dass die Farben kombinierbar sind. Eine gute Trendfarbe zeigt sich <strong>kombinationsfreudig und vielseitig<\/strong>.<\/p>\n<h2>Pantone Farbe des Jahres 2022: Very Peri<\/h2>\n<p>Jedes Jahr wird mit Spannung die neue Pantone-Farbe erwartet: Mit <strong>\u201eVery Peri\u201c<\/strong> schl\u00e4gt das US-amerikanische Farbinstitut den entgegengesetzten Weg zu 2021 ein, als der Gelbton \u201eIlluminating\u201c das Farb-Jahr bestimmte.<\/p>\n<p>\u201eVery Peri\u201c ist ein Lila-Blauton mit leicht r\u00f6tlichem Unterton. Gef\u00fchrt wird er unter der Bezeichnung <strong>Pantone 17-3938<\/strong>. Gef\u00e4llt Ihnen der Farbton, so k\u00f6nnen Sie ihn \u00fcber diese Chiffre genau bestimmen. Das Blau-Lila ist eine warme und kraftvolle Farbe, die Zuversicht und Freude ausdr\u00fcckt.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4884\" aria-describedby=\"caption-attachment-4884\" style=\"width: 517px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4884\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-1024x1024.jpg\" alt=\"Pantone Very Peri\" width=\"517\" height=\"517\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-1024x1024.jpg 1024w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-300x300.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-150x150.jpg 150w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-768x768.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-1536x1536.jpg 1536w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-696x696.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-1068x1068.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03-420x420.jpg 420w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/PantoneBoxset03.jpg 1920w\" sizes=\"(max-width: 517px) 100vw, 517px\" \/><figcaption id=\"caption-attachment-4884\" class=\"wp-caption-text\">Foto: Pantone<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Dulux Farbe des Jahres 2022: Bright Skies\u2122<\/h2>\n<p>Der Farben- und Lackhersteller Dulux ver\u00f6ffentlicht in Kooperation mit internationalen Designexperten jedes Jahr die \u201eDulux Farbe des Jahres\u201c. In 2022 fiel die Wahl auf <strong>Bright Skies\u2122<\/strong>, einen luftigen und leichten Blauton. Der unaufdringliche Farbton \u00f6ffnet R\u00e4ume und l\u00e4sst einen frischen Wind durch die Wohnung wehen. Bright Skies\u2122 steht f\u00fcr eine optimistische Haltung und einen erfrischenden Neuanfang.<\/p>\n<figure id=\"attachment_4886\" aria-describedby=\"caption-attachment-4886\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-4886 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/akzonobel-dulux-color-of-the-year-2022.jpg\" alt=\"akzonobel-dulux 2022 Farbe des Jahres\" width=\"640\" height=\"360\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/akzonobel-dulux-color-of-the-year-2022.jpg 640w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/akzonobel-dulux-color-of-the-year-2022-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-4886\" class=\"wp-caption-text\">Foto: Akzo Nobel<\/figcaption><\/figure>\n<h2>Farbige Fliesen und ihre Wirkung<\/h2>\n<p>Ob an der Wand oder auf dem Boden, die Farbe der Fliesen beeinflusst, wie wir den Raum wahrnehmen, und wie wohl wir uns f\u00fchlen. Die aktuellen Trends deuten dabei in eine konkrete Richtung: Gesch\u00e4tzt werden vor allem Fliesenfarben, die frisch und luftig wirken. Durch die Leichtigkeit muntern uns die Fliesen auf und haben eine belebende Wirkung. Besonders naturnahe und sanfte Farbt\u00f6ne kommen bei der Raumgestaltung zum Einsatz.<\/p>\n<p>Je farbiger und bunter die Fliesen sind, desto vorsichtiger sollten Sie mit den Fl\u00e4chen umgehen. Mosaikfliesen mit Mustern und kr\u00e4ftigen Farben kommen als Bodenfliese in weitl\u00e4ufigen R\u00e4umen zur Geltung. Als Wandfliese sind sie besonders auf kleinen Fl\u00e4chen in K\u00fcchen und B\u00e4dern eine gute Wahl. Auch der Stil der Fliese ist eng mit Farbe und Wirkung verkn\u00fcpft.<\/p>\n<h2>Bunte Fliesen in verschiedenen Stilen<\/h2>\n<h3>Metrofliesen<\/h3>\n<p>Typisch ist die rechteckige Form und die gefaste Kante (abgeschr\u00e4gt). Metrofliesen gibt es gl\u00e4nzend und matt. F\u00fcr die Wandgestaltung stehen Ihnen klassische Varianten aus der <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Tau-Ceramica\/Tau-Ceramica-Classic\" target=\"_blank\" rel=\"noopener\">Classic-Serie von Tau Ceramica<\/a> zur Auswahl. Auch Villeroy und Boch hat eine <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Villeroy-und-Boch\/metro-flair\/\" target=\"_blank\" rel=\"noopener\">Metrofliese Flair im Portfolio<\/a>.<\/p>\n<figure id=\"attachment_2594\" aria-describedby=\"caption-attachment-2594\" style=\"width: 895px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-2594 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow.jpg\" alt=\"Metrofliese Snow VB\" width=\"895\" height=\"625\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow.jpg 895w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow-300x209.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow-768x536.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow-100x70.jpg 100w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow-696x486.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/06\/Villery-Boch-Metro-Snow-601x420.jpg 601w\" sizes=\"(max-width: 895px) 100vw, 895px\" \/><figcaption id=\"caption-attachment-2594\" class=\"wp-caption-text\">Die Metro Flair von Villeroy und Boch ist in den Farben Alabaster, Midnight, Clay, Light Dove und Berry erh\u00e4ltlich. Foto: Werksbild<\/figcaption><\/figure>\n<h3>Azulejo<\/h3>\n<p>Die portugiesisch-spanischen Fliesen werden f\u00fcr ihre auff\u00e4lligen Ornamente, Muster und pr\u00e4chtigen Farbenspiele gesch\u00e4tzt. Bei ihnen spielen nat\u00fcrliche Braunt\u00f6ne, Wei\u00df und nat\u00fcrlich mediterrane Blaut\u00f6ne eine wichtige Rolle. Die quadratischen Fliesen stehen heutzutage auch sinnbildlich f\u00fcr einen Vintage-Stil. Passend dazu bietet die <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/Vintage\/\" target=\"_blank\" rel=\"noopener\">Vintage-Serie von Prime Collection<\/a> eine Vielzahl an dekorativen Boden- und Wandfliesen.<\/p>\n<figure id=\"attachment_4890\" aria-describedby=\"caption-attachment-4890\" style=\"width: 672px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/Vintage\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4890\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1024x683.jpg\" alt=\"Vintage Prime Collection\" width=\"672\" height=\"449\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1024x683.jpg 1024w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-300x200.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-768x512.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-696x464.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1068x712.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-630x420.jpg 630w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC.jpg 1200w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/><\/a><figcaption id=\"caption-attachment-4890\" class=\"wp-caption-text\">Wer sich das Flair vergangener Jahrzehnte ins Haus holen will, findet mit der Kollektion Vintage von PrimeCollection glasierte Feinsteinzeugfliesen im nostalgischen Used-Design.<\/figcaption><\/figure>\n<h3>Fliesen in Zementoptik<\/h3>\n<p>Im Jugendstil erlebten Fliesen in Zementoptik ihre Hochzeit. Diese Zeit kommt nun wieder und wird hierzulande ganz einfach als retro bezeichnet. \u00c4hnlich wie Azulejo-Fliesen spielt auch die Zementoptik mit grafischen, floralen und ornamentalen Mustern. Farblich bekommen sie die Fliesen in zarten Blaut\u00f6nen, Rostrot oder Sandbeige. Wer es reduziert und elegant mag, w\u00e4hlt Zementoptik-Fliesen in schwarz-wei\u00dfen Mustern.<\/p>\n<h3>Fliesen in Metalloptik<\/h3>\n<p>Funkelnde Akzente setzen Sie mit Fliesen aus der <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Viva\/Metallica\/\" target=\"_blank\" rel=\"noopener\">Metallica-Serie von Viva<\/a>. Durch die glasierte und gl\u00e4nzende Oberfl\u00e4che beginnen die Feinsteinzeugfliesen in gr\u00fcn und blau zu schimmern. Die recht dunklen Farbt\u00f6ne eignen sich f\u00fcr gro\u00dfe Fl\u00e4chen und hohe R\u00e4ume. Stichwort: Industrial und Fabrik-Charme.<\/p>\n<figure id=\"attachment_4892\" aria-describedby=\"caption-attachment-4892\" style=\"width: 543px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Viva\/Metallica\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4892\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-724x1024.jpg\" alt=\"Viva Serie Metallica\" width=\"543\" height=\"768\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-724x1024.jpg 724w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-212x300.jpg 212w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-768x1087.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-696x985.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD-297x420.jpg 297w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Metallica-Steel-120x278-Brick-Blue-Amb-Poltrona-SD.jpg 848w\" sizes=\"(max-width: 543px) 100vw, 543px\" \/><\/a><figcaption id=\"caption-attachment-4892\" class=\"wp-caption-text\">Sie lieben k\u00fchles Brick-Design in schillernden Oberfl\u00e4chen? Mit der Serie Metallica kommt von VIVA eine Fliesenkollektion auf den Markt, die das k\u00fchle Blech f\u00fcr den Wohnraum neu interpretiert. Die Metalloptik wird in Farbvarianten von Schwarz u\u0308ber Schiefergrau bis hin zu Stahlfarben und Wei\u00df nachempfunden. Foto: Werksbild<\/figcaption><\/figure>\n<h3>Terrazzo<\/h3>\n<p>Wer an bunte Fliesen denkt, hat sofort Terrazzofliesen im Kopf. Durch Zuschl\u00e4ge erhalten die Fliesen einen gesprenkelten Look, der sich beliebig farblich gestalten l\u00e4sst. Grau, Schwarz, Wei\u00df, Braun in den verschiedensten Facetten pr\u00e4gen die Auswahl der <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/Frammenti\/\" target=\"_blank\" rel=\"noopener\">Frammenti-Serie von Prime Collection<\/a>. Hauptsache, es bleibt nat\u00fcrlich!<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2989\" aria-describedby=\"caption-attachment-2989\" style=\"width: 900px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/Frammenti\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2989 size-full\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product.jpg\" alt=\"PrimeCollection Frammenti Fliesen\" width=\"900\" height=\"900\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product.jpg 900w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product-150x150.jpg 150w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product-300x300.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product-768x768.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product-696x696.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2019\/12\/299456_Product-420x420.jpg 420w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-2989\" class=\"wp-caption-text\">Foto: Werksbild<\/figcaption><\/figure>\n<h2>Fazit<\/h2>\n<p>Sie sehen: Fliesen k\u00f6nnen heute mehr als nur reines Wei\u00df hervorbringen. Bunte Fliesen bieten die M\u00f6glichkeit zahlreicher Kombinationsm\u00f6glichkeiten f\u00fcr kreative Raumideen. Sprechen Sie uns an. Gemeinsam setzen wir auch Ihr n\u00e4chstes Projekt um:\u00a0<a href=\"mailto:info@franke-raumwert.de\">info@franke-raumwert.de<\/a><\/p>\n<div class=\"shariff\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fmit-farbe-einrichten-bunte-fliesen-fuer-ihr-zuhause%2F2022%2F05\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fmit-farbe-einrichten-bunte-fliesen-fuer-ihr-zuhause%2F2022%2F05&text=Mit%20Farbe%20einrichten%3A%20Bunte%20Fliesen%20f%C3%BCr%20Ihr%20Zuhause\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fmit-farbe-einrichten-bunte-fliesen-fuer-ihr-zuhause%2F2022%2F05&media=https%3A%2F%2Fwww.franke-raumwert.de%2Faktuelles%2Fwp-content%2Fuploads%2F2022%2F05%2FAMB-VICTORIAN-3-HQ.jpg&description=Mit%20Farbe%20einrichten%3A%20Bunte%20Fliesen%20f%C3%BCr%20Ihr%20Zuhause\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span class=\"shariff-text\">merken<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Bringen Sie Farbe in Ihre Wohnung! Keramische Fliesen bieten vielf\u00e4ltige Farben und Muster, welche die Einrichtung pr\u00e4gen und zur Raumwirkung beitragen. Wir zeigen Ihnen, welche Farben in der Innenraumgestaltung im Trend liegen und welche Fliesen f\u00fcr Farbtupfer sorgen. Welche Farben sind modern? Eine Frage, die sich nur schwer beantworten l\u00e4sst. Schlie\u00dflich weichen die j\u00e4hrlichen Farbtrends [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"Mit Farbe einrichten: Bunte Fliesen f\u00fcr Ihr Zuhause - Franke Raumwert","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"fliesen bunt","footnotes":""},"categories":[3],"tags":[],"class_list":["post-4881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wohnideen"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/4881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=4881"}],"version-history":[{"count":10,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/4881\/revisions"}],"predecessor-version":[{"id":4896,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/4881\/revisions\/4896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/4889"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=4881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=4881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=4881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}