{"id":5124,"date":"2022-11-03T14:05:00","date_gmt":"2022-11-03T13:05:00","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=5124"},"modified":"2024-01-26T17:13:04","modified_gmt":"2024-01-26T16:13:04","slug":"wasser-im-bad-sparen-wie-geht-das","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/wasser-im-bad-sparen-wie-geht-das\/2022\/11","title":{"rendered":"Haushaltstipp: Wasser im Bad sparen \u2013 wie geht das?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Was tun, um effektiv Wasser im Badezimmer zu sparen? Wir stellen Ihnen die wichtigsten technischen L\u00f6sungen f\u00fcr einen geringeren Wasserverbrauch vor und geben Ihnen kurze Tipps, wie das eigene Verhalten zur Einsparung beitragen kann.\u00a0<\/strong><\/p>\n<p>Steigende Energiekosten belasten unsere Portemonnaies. Doch was hat das mit unserem Wasserverbrauch zu tun? Viel, denn auch die Bereitstellung und Aufbereitung von Trinkwasser und Warmwasser wird durch h\u00f6here Energiekosten teurer. Der t\u00e4gliche Verbrauch liegt bei ca. 130 Liter pro Person t\u00e4glich, wobei ca. 60 Prozent allein auf den Wasserverbrauch im Bad entfallen: Duschen, H\u00e4ndewaschen, Toilette, um nur die gr\u00f6\u00dften Verbraucher zu nennen.<\/p>\n<h2>Effektiv Wasser im Bad sparen &#8211; L\u00f6sungen<\/h2>\n<h3>Badewanne<\/h3>\n<p>Beim Baden ist <strong>kaum signifikantes Einsparpotenzial<\/strong> vorhanden, ohne auf Komfort zu verzichten. Niemand m\u00f6chte schlie\u00dflich in einer halbvollen Badewanne sitzen. Es gibt jedoch zwei Optionen: Zum einen k\u00f6nnen Sie <strong>auf Vollb\u00e4der verzichten<\/strong> oder zumindest stark reduzieren, da bei einem Badegang bis zu 200 Liter Wasser verbraucht werden. Zum anderen k\u00f6nnen Sie die <strong>Wassertemperatur senken<\/strong>, z. B. um 2-3 \u00b0C. Das spart zumindest Energiekosten, da das Wasser weniger stark erw\u00e4rmt wird. Ersetzen Sie aber am besten die Badewanne durch die Dusche, bei der nur 60 l bis 80 l Wasser durchschnittlich verbraucht werden.<\/p>\n<figure id=\"attachment_4769\" aria-describedby=\"caption-attachment-4769\" style=\"width: 696px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Love-Tiles\/Precious-3242\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4769 size-large\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-1024x607.jpg\" alt=\"Love Tiles Precious\" width=\"696\" height=\"413\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-1024x607.jpg 1024w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-300x178.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-768x455.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-696x412.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-1068x633.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg-709x420.jpg 709w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/01\/220-220-27-27-preciouswcfemmerylstreepamb-jpg.jpg 1200w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-4769\" class=\"wp-caption-text\">Inspiriert vom ber\u00fchmten Calacatta-Marmor hat der Hersteller LoveTiles die glasierte Feinsteinzeugfliesen-Serie Precious entwickelt. Die Kollektion taucht B\u00e4der und Wohnr\u00e4ume mit ihren strahlend hellen Oberfl\u00e4chen in eine elegante Atmosph\u00e4re und ist f\u00fcr W\u00e4nde und B\u00f6den geeignet. Foto: Werksbild<\/figcaption><\/figure>\n<h3>Dusche<\/h3>\n<p>Richtig Wasser sparen l\u00e4sst sich beim Duschen! Das bedeutet aber nicht zwingend, dass Sie auf Komfort verzichten m\u00fcssen. Die 30 l pro Minute durchlassende Regendusche sollte dennoch einem <strong>Duschsparkopf<\/strong> weichen, der den Verbrauch auf 9 l pro Minute reduziert. Ebenfalls helfen <strong>Perlatoren<\/strong>. Das sind Strahlregler, die dem Durchfluss Luft beimischen und den Wasserverbrauch verringern. Der Wasserstrahl bleibt dabei kr\u00e4ftig und gleichm\u00e4\u00dfig breit.<\/p>\n<p>Auch \u00fcber die Temperaturen l\u00e4sst sich viel Energie sparen. \u00c4hnlich wie beim Baden k\u00f6nnen Sie auch beim Duschen die Temperatur um einige Grad senken. Regeln Sie die H\u00f6chsttemperatur und Durchschnittstemperatur \u00fcber ein <strong>Thermostat<\/strong>. Das verhindert, dass starke Temperaturwechsel stattfinden und stattdessen die Wassertemperatur sich in einem festgelegten Rahmen bewegt.<\/p>\n<figure id=\"attachment_4890\" aria-describedby=\"caption-attachment-4890\" style=\"width: 696px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/PrimeCollection\/vintage-wall\/\"><img decoding=\"async\" class=\"wp-image-4890 size-large\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1024x683.jpg\" alt=\"Vintage Prime Collection\" width=\"696\" height=\"464\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1024x683.jpg 1024w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-300x200.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-768x512.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-696x464.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-1068x712.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC-630x420.jpg 630w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2022\/05\/Vintage-PC.jpg 1200w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-4890\" class=\"wp-caption-text\">Kollektion Vintage Wall von PrimeCollection mit glasierten Feinsteinzeugfliesen im nostalgischen Used-Design. Foto: Werksbild<\/figcaption><\/figure>\n<h3>Waschbecken<\/h3>\n<p>Analog zur Dusche verhindern <strong>Strahlregler und Durchflussbegrenzer<\/strong> auch bei der Waschbeckenarmatur einen hohen Wasserverbrauch. Zus\u00e4tzlich gibt es f\u00fcr Armaturen auch <strong>Wassersparkartuschen f\u00fcr Einhebelmischbatterien<\/strong>, die Sie ganz einfach nachr\u00fcsten k\u00f6nnen. Ein Widerstand blockiert den Hebel, sodass Sie nicht \u00fcber einen gewissen Durchlass kommen.<\/p>\n<p>Noch effizienter funktionieren <strong>Armaturen mit Sensortechnik<\/strong> wie Infrarotsensoren. Der Wasserhahn l\u00e4sst nur Wasser durch, sobald H\u00e4nde im Waschbecken sind und die Lichtschranke durchbrechen. Beispielsweise nutzen moderne \u00f6ffentliche B\u00e4der und WCs diese Technik, da so ein besserer hygienischer Zustand gew\u00e4hrleistet wird.<\/p>\n<h3>Toilette<\/h3>\n<p>Das gr\u00f6\u00dfte Einsparpotenzial bei der Toilette liegt im optimalen Sp\u00fclvorgang. Moderne Sp\u00fclk\u00e4sten verf\u00fcgen \u00fcber eine <strong>Start-Stopp-Funktion<\/strong> oder \u00fcber eine <strong>2-Mengen-Funktion<\/strong>. Bei Erster unterbrechen Sie \u00fcber die Stopp-Taste den Sp\u00fclvorgang. Bei der 2-Mengen-Sp\u00fclung bietet die Toilette eine gro\u00dfe und eine kleine Taste. Sp\u00fclt die Toilette beim Druck auf die gro\u00dfe Taste mit ca. 6 l, sind es bei der kleinen Taste gerade einmal 3 l.<\/p>\n<p>Beachten Sie jedoch, dass eine gewisse Menge Sp\u00fclwasser n\u00f6tig ist, um eine st\u00f6rungsfreie Funktion der Abwasserrohre und Kanalisation sicherzustellen. Flie\u00dft nicht eine Mindestmenge an Sp\u00fclwasser, k\u00f6nnen sich Ablagerungen bilden, die wiederum zu Verstopfungen der Rohrleitungen f\u00fchren.<\/p>\n<figure id=\"attachment_4600\" aria-describedby=\"caption-attachment-4600\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-4600\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big.jpg\" alt=\"Franke-Raumwert-fliesenausstellung-menden\" width=\"900\" height=\"596\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big.jpg 900w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big-300x199.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big-768x509.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big-696x461.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2021\/10\/Franke-Raumwert-fliesenausstellung-menden_05-big-634x420.jpg 634w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-4600\" class=\"wp-caption-text\">Moderne Sanit\u00e4robjekte wie Waschbecken, WCs und Armaturen in der Fliesenausstellung von Franke Raumwert. Foto: Werksbild<\/figcaption><\/figure>\n<p>Richtig viel Wasser sparen Sie, wenn Sie bei der Badplanung ein <strong>Urinal<\/strong> installieren. Diese ben\u00f6tigen nur ein Bruchteil des Wassers, das bei der normalen Toilettensp\u00fclung anf\u00e4llt. Zudem gibt es spezielle Trockenurinale. Bei Trockenurinalen befindet sich eine biologisch abbaubare Sperrfl\u00fcssigkeit im Siphon. Da sie hydrophob ist, l\u00e4sst sie den schwereren Urin hindurch und bildet eine nat\u00fcrliche Sperre zum Abfluss. So bleiben schlechte Ger\u00fcche in den Rohren und dringen nicht durch das Urinal nach drau\u00dfen.<\/p>\n<h3>Waschmaschine<\/h3>\n<p>Da in vielen Haushalten die Waschmaschinenanschl\u00fcsse im Bad anliegen, l\u00e4sst sich auch \u00fcber die Waschmaschine viel Wasser im Bad einsparen. Nutzen Sie z. B. f\u00fcr leicht bis m\u00e4\u00dfig verschmutzte Kleidung das <strong>Eco-Programm<\/strong>, das ohne Vorw\u00e4sche w\u00e4scht und Wasser l\u00e4nger benutzt. Die Waschvorg\u00e4nge dauern zwar l\u00e4nger, sparen aber viel Energie und Wasser.<\/p>\n<p>Ein weiterer Tipp: <strong>Waschmaschine voll beladen<\/strong>. Sollten alte Waschmaschinen maximal bis zu Dreiviertel ihres Volumens beladen werden, funktionieren moderne Ger\u00e4te am besten bei voller Ladung.<\/p>\n<h2>Eigenes Verhalten anpassen<\/h2>\n<ul>\n<li>Duschen statt baden!<\/li>\n<li>Wassertemperatur beim Duschen und Baden um ein paar Grad reduzieren.<\/li>\n<li>Wasserhahn zu! Beim Einseifen, Rasieren und Z\u00e4hneputzen Wasser nicht durchg\u00e4ngig laufen lassen.<\/li>\n<li>Kaltes Wasser beim H\u00e4ndewaschen verwenden.<\/li>\n<li>Kaltes Wasser auffangen und zum Putzen oder Blumengie\u00dfen verwenden.<\/li>\n<\/ul>\n<h2>Bew\u00e4hrte Qualit\u00e4t bei Franke Raumwert<\/h2>\n<p>Egal, f\u00fcr welche Badezimmer-Ausstattung man sich entscheidet: Kunden profitieren von zahlreichen Angeboten in der<strong> umfangreichen Fliesen- und Sanit\u00e4rausstellung von Franke Raumwert im sauerl\u00e4ndischen Menden oder im <a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/\" target=\"_blank\" rel=\"noopener\">Online-Shop<\/a><\/strong>. Sofern Sie sich Unterst\u00fctzung bei der Planung oder Umsetzung w\u00fcnschen, sind unsere Berater und Fliesenverleger f\u00fcr Sie da.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Was tun, um effektiv Wasser im Badezimmer zu sparen? Wir stellen Ihnen die wichtigsten technischen L\u00f6sungen f\u00fcr einen geringeren Wasserverbrauch vor und geben Ihnen kurze Tipps, wie das eigene Verhalten zur Einsparung beitragen kann.\u00a0 Steigende Energiekosten belasten unsere Portemonnaies. Doch was hat das mit unserem Wasserverbrauch zu tun? Viel, denn auch die Bereitstellung und [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"Haushaltstipp: Wasser im Bad sparen \u2013 wie geht das?","_seopress_titles_desc":"Was tun, um Wasser im Bad zu sparen? Wir stellen Ihnen Haushaltstipps vor, wie Sie im Handumdrehen sparen k\u00f6nnen. \u00a0","_seopress_robots_index":"","_seopress_analysis_target_kw":"Wasser sparen Bad","footnotes":""},"categories":[32,19],"tags":[],"class_list":["post-5124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bad","category-sanitaer"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=5124"}],"version-history":[{"count":8,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5124\/revisions"}],"predecessor-version":[{"id":5217,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5124\/revisions\/5217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=5124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=5124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=5124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}