{"id":5620,"date":"2023-06-26T17:24:50","date_gmt":"2023-06-26T15:24:50","guid":{"rendered":"https:\/\/www.franke-raumwert.de\/aktuelles\/?p=5620"},"modified":"2024-01-26T17:10:43","modified_gmt":"2024-01-26T16:10:43","slug":"fuenf-einfache-tipps-fuer-den-entspannten-fliesenkauf","status":"publish","type":"post","link":"https:\/\/www.franke-raumwert.de\/aktuelles\/fuenf-einfache-tipps-fuer-den-entspannten-fliesenkauf\/2023\/06","title":{"rendered":"F\u00fcnf einfache Tipps f\u00fcr den entspannten Fliesenkauf"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Bauprojekte k\u00f6nnen stressig sein. Damit alles glatt l\u00e4uft kommen hier f\u00fcnf Tipps f\u00fcr den Fliesenkauf, die beim Bodenbelag helfen.<\/strong><\/p>\n<p>Steht ein neues Bauprojekt an, muss einiges beachtet werden. Neben Raumaufteilung, Beleuchtung und Mobiliar geh\u00f6rt ein passender Boden- und Wandbelag dazu. Besonders im Trend stehen aktuell die langlebigen und robusten Fliesenbel\u00e4ge.<\/p>\n<h2>5 Tipps f\u00fcr den Fliesenkauf<\/h2>\n<p>Damit beim Einbau nichts schief geht, ist eine gr\u00fcndliche Planung rund um die neue Ausstattung wichtig. Um Fehler zu vermeiden, kommen hier f\u00fcnf Dinge, auf die Sie vor und w\u00e4hrend des Fliesenkaufes achten sollten:<\/p>\n<h3>1. Auswahl treffen<\/h3>\n<p>Zuallererst steht die Auswahl an. Bei der riesigen Anzahl an Fliesen kann schnell der \u00dcberblick verloren werden. Lieber die in Holz- oder Steinoptik? Oder vielleicht doch Beton? Um sich m\u00f6glichst lange am Anblick erfreuen zu k\u00f6nnen, sollten Sie sich vor dem Kauf absolut sicher sein. Hilfe leisten dabei Muster. Lassen Sie sich diese einfach von den favorisierten Fliesen nach Hause liefern und vergleichen Sie sie ganz in Ruhe.<\/p>\n<h3>2. Gen\u00fcgend Zeit einplanen<\/h3>\n<p>Ist die Auswahl dann getroffen, kann endlich bestellt werden. \u00c4rgerlich wird es, wenn die penibel ausgew\u00e4hlte Fliese dann nicht auf Lager ist. Die Lieferzeiten k\u00f6nnen variieren und den Bau unn\u00f6tig in die L\u00e4nge ziehen. Besser ist es also, eine Vorlaufzeit f\u00fcr die Auswahl einzuplanen und fr\u00fchzeitig beim Fliesenh\u00e4ndler anzufragen.<\/p>\n<h3>3. Menge korrekt berechnen<\/h3>\n<p>Sie sollten immer mindestens zehn Prozent des ben\u00f6tigten Materials an Verschnitt einplanen. Je gr\u00f6\u00dfer die Fliesen sind, desto mehr Verschnitt entsteht. F\u00fcr Wandfliesen ab 30cm x 90cm und Bodenfliesen ab 80cm x 80cm k\u00f6nnen es auch 15 Prozent sein. Hierbei gilt das Motto: Besser zu viel als zu wenig.<\/p>\n<figure id=\"attachment_5625\" aria-describedby=\"caption-attachment-5625\" style=\"width: 694px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.franke-raumwert.de\/Fliesen\/Flaviker\/supreme-memories\/\"><img alt=\"\" fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-5625\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-694x1024.jpg\" alt=\"\" width=\"694\" height=\"1024\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-694x1024.jpg 694w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-203x300.jpg 203w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-768x1133.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-1041x1536.jpg 1041w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-1388x2048.jpg 1388w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-696x1027.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-1068x1575.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-285x420.jpg 285w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/B_04-SUPREME-MEMORIES-BIANCO-VAGLI-NAT.R.60X120BRECCIA-IMPERIALE-N.R.120X28017-1-1920x2832.jpg 1920w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/a><figcaption id=\"caption-attachment-5625\" class=\"wp-caption-text\">Kollektion Supreme Memories in Marmoroptik des Herstellers Flaviker. Foto: Werksfoto<\/figcaption><\/figure>\n<h3>4. Eigenschaften der Fliese beachten<\/h3>\n<p>Je nachdem wo Sie den Bodenbelag verlegen wollen, sind besondere Eigenschaften der Fliese gefragt. Im Badezimmer oder Terrassenbereich ist zum Beispiel Rutschfestigkeit durch strukturierte Oberfl\u00e4chen ein Muss. Befassen Sie sich vorher mit den Anforderungen und M\u00f6glichkeiten, diese umzusetzen. Im Duschbereich kann etwa mit sch\u00f6nen Mosaiken gearbeitet werden, um einen sicheren Stand zu gew\u00e4hren und Unf\u00e4lle zu vermeiden.<\/p>\n<h3>5. Indirekte Beleuchtung und Accessoires vorher festlegen<\/h3>\n<p>Wenn Sie planen, indirekte Lichtquellen wie Liprotec oder Wandnischen in ihre R\u00e4ume einzubauen, muss dies unbedingt schon vor der Fliesenverlegung ber\u00fccksichtigt werden. Die richtige Reihenfolge beim Bauen ist hier besonders wichtig. Edelstahlablagen m\u00fcssen beispielsweise schon in die Fuge mit eingearbeitet und Technik f\u00fcr Beleuchtung schon bei der Verlegung angebracht werden. Sind die Fliesen erst einmal fest, ist es nachtr\u00e4glich schwierig, diese Dinge noch hinzuzuf\u00fcgen.<\/p>\n<figure id=\"attachment_5627\" aria-describedby=\"caption-attachment-5627\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.franke-raumwert.de\/Zubehoer\/Fliesenbeleuchtung\/\"><img alt=\"\" decoding=\"async\" class=\"size-large wp-image-5627\" src=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-1024x1024.jpg\" alt=\"\" width=\"696\" height=\"696\" srcset=\"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-1024x1024.jpg 1024w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-300x300.jpg 300w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-150x150.jpg 150w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-768x768.jpg 768w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-696x696.jpg 696w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-1068x1068.jpg 1068w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1-420x420.jpg 420w, https:\/\/www.franke-raumwert.de\/aktuelles\/wp-content\/uploads\/2023\/06\/Schlueter-LIPROTEC_01_1200x1200px-1.jpg 1200w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-5627\" class=\"wp-caption-text\">Liprotec Fliesenbeleuchtung finden Sie bei Franke Raumwert im Blog. Foto: Werksbild<\/figcaption><\/figure>\n<h2>Fliesenkauf Tipps mit Franke Raumwert<\/h2>\n<p>Ein kleiner Extra-Tipp am Ende: Damit ihre Fliesen fachm\u00e4nnisch und sauber angebracht werden, ist es extrem hilfreich, einen Spezialisten hinzuzuziehen. Der sauerl\u00e4ndische Fliesenlegerbetrieb Franke Raumwert zum Beispiel unterst\u00fctzt sie von Tipp eins bis f\u00fcnf, plant gemeinsam mit Ihnen Ihre Projekte und steht mit Rat und Tat dank der hochqualifizierten Mitarbeiter zur Seite.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Bauprojekte k\u00f6nnen stressig sein. Damit alles glatt l\u00e4uft kommen hier f\u00fcnf Tipps f\u00fcr den Fliesenkauf, die beim Bodenbelag helfen. Steht ein neues Bauprojekt an, muss einiges beachtet werden. Neben Raumaufteilung, Beleuchtung und Mobiliar geh\u00f6rt ein passender Boden- und Wandbelag dazu. Besonders im Trend stehen aktuell die langlebigen und robusten Fliesenbel\u00e4ge. 5 Tipps f\u00fcr den [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"F\u00fcnf einfache Tipps f\u00fcr den entspannten Fliesenkauf","_seopress_titles_desc":"Bauprojekte k\u00f6nnen stressig sein. Damit alles glatt l\u00e4uft kommen hier f\u00fcnf Tipps f\u00fcr den Fliesenkauf, die beim Bodenbelag helfen.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Fliesenkauf Tipps","footnotes":""},"categories":[31],"tags":[],"class_list":["post-5620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-planung"],"_links":{"self":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/comments?post=5620"}],"version-history":[{"count":6,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5620\/revisions"}],"predecessor-version":[{"id":5636,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/posts\/5620\/revisions\/5636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media\/5624"}],"wp:attachment":[{"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/media?parent=5620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/categories?post=5620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franke-raumwert.de\/aktuelles\/wp-json\/wp\/v2\/tags?post=5620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}